{"id":8223,"date":"2022-09-16T20:33:13","date_gmt":"2022-09-16T23:33:13","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=8223"},"modified":"2023-01-10T12:07:25","modified_gmt":"2023-01-10T15:07:25","slug":"controle-cigarrinha-do-milho","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/controle-cigarrinha-do-milho\/","title":{"rendered":"Como controlar a cigarrinha-do-milho e o complexo de enfezamentos atrav\u00e9s da nutri\u00e7\u00e3o das plantas?"},"content":{"rendered":"<p>Voc\u00ea j\u00e1 observou o avermelhamento ou amarelecimento generalizado ou estrias esbranqui\u00e7adas nas plantas de milho, associadas a quedas de produtividade? Saiba que esses sintomas podem estar associados ao complexo de enfezamentos do milho, que s\u00e3o transmitidos pelo seu vetor: a cigarrinha-do-milho. Esse ainda \u00e9 um problema sem solu\u00e7\u00e3o que tem se alastrado ano ap\u00f3s ano nas lavouras brasileiras, mas que pode ser controlado e mitigado usando um conjunto de boas pr\u00e1ticas no campo, que incluem a nutri\u00e7\u00e3o vegetal.<\/p>\n<p>Para falar sobre esse assunto, o agr\u00f4nomo com mais de 15 anos de experi\u00eancia e criador do movimento DeOlhoNaPlanta, Lu\u00eds Eduardo Salvatico, participou do <strong>\u201cEncontro com Gigantes \u2013 Cigarrinha-do-milho: como o pot\u00e1ssio pode contribuir no manejo desta praga?\u201d<\/strong>.<\/p>\n<p>O evento foi promovido pela Verde Agritech, empresa que produz os fertilizantes <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/entenda-o-que-e-o-baks-e-as-suas-vantagens-para-uma-nova-agricultura\/\">BAKS<sup>\u00ae<\/sup><\/a>, <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/entenda-o-que-e-o-k-forte-e-quais-beneficios-o-fertilizante-proporciona-para-a-agricultura\/\">K Forte<sup>\u00ae<\/sup><\/a>, K Forte Boro e <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/conheca-o-silicio-forte-e-a-importancia-do-silicio-na-agricultura\/\">Sil\u00edcio Forte<\/a>, no dia 15 de setembro de 2022.<\/p>\n<p>Voc\u00ea pode conferir a conversa, mediada pela Dra. Rafaela Santos, na \u00edntegra pelo link:<\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_29289\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/6TetGHaObF0?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<h2>Quais s\u00e3o os impactos da cigarrinha-do-milho?<\/h2>\n<p>Nos \u00faltimos anos, a <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/como-controlar-a-cigarrinha-do-milho-de-forma-efetiva\/\">cigarrinha-do-milho<\/a> tem atra\u00eddo a aten\u00e7\u00e3o de muitos agricultores, mas n\u00e3o por causa dos impactos diretos que ela causa enquanto um inseto-praga na lavoura.<\/p>\n<p>A causa principal da preocupa\u00e7\u00e3o com as infesta\u00e7\u00f5es desse inseto nas lavouras \u00e9 o fato de que ele \u00e9 um importante vetor dos tr\u00eas principais agentes patog\u00eanicos que causam o complexo de enfezamento do milho.<\/p>\n<p>\u201cO dano da cigarrinha como inseto, faz com que ela seja uma praga de baixa import\u00e2ncia econ\u00f4mica. O grande problema acontece \u00e9 quando ela atua como vetor, uma praga que transmite o complexo de enfezamentos.\u201d, pontuou o agr\u00f4nomo Lu\u00eds Eduardo Salvatico<\/p>\n<p>Esse inseto pequeno de cor branco-palha, quando infectado, \u00e9 capaz de infectar as plantas com fitopat\u00f3genos durante a sua alimenta\u00e7\u00e3o, incluindo aqueles que causam o complexo de enfezamento do milho:<\/p>\n<ul>\n<li>As bact\u00e9rias do grupo fitoplasma;<\/li>\n<li>As bact\u00e9rias do grupo espiroplasma;<\/li>\n<li>O v\u00edrus <em>Maize rayado fino virus<\/em>.<\/li>\n<\/ul>\n<p>Enquanto as bact\u00e9rias do grupo fitoplasma e espiroplasma s\u00e3o respons\u00e1veis por causar o enfezamento-vermelho e o enfezamento-p\u00e1lido do milho, respectivamente, e \u00e9 atribu\u00eddo ao v\u00edrus a virose da risca.<\/p>\n<p>Lu\u00eds Eduardo Salvatico explicou que essas doen\u00e7as podem trazer muitos preju\u00edzos para a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/potassio-milho-para-silagem\/\">produtividade do milho<\/a>, uma vez que elas levam \u00e0 redu\u00e7\u00e3o da capacidade de absor\u00e7\u00e3o, assimila\u00e7\u00e3o de nutrientes e produ\u00e7\u00e3o de fotoassimilados das plantas e ainda reduzem a taxa de crescimento do milho.<\/p>\n<p>Entretanto, como ainda n\u00e3o existe nenhuma tecnologia ou produto capaz de conter a progress\u00e3o do complexo dos enfezamentos, grande parte dos esfor\u00e7os para conten\u00e7\u00e3o dessa doen\u00e7a fica concentrada no controle do seu vetor: a cigarrinha-do milho.<\/p>\n<p>Segundo Salvatico, o controle efetivo da cigarrinha-do-milho normalmente envolve um conjunto de boas pr\u00e1ticas, adotando t\u00e1ticas preventivas para reduzir a popula\u00e7\u00e3o de insetos e fonte de in\u00f3culos. Mesmo assim, o controle desse inseto-praga no Brasil \u00e9 cercado de v\u00e1rios desafios:<\/p>\n<p>\u201cA planta hospedeira da cigarrinha \u00e9 o milho, ou seja, a praga precisa dela para se multiplicar. Mas, quando n\u00e3o tem milho, ela pode usar como ref\u00fagio algumas outras esp\u00e9cies, como milheto, capim coloni\u00e3o, braqui\u00e1ria dentro outras esp\u00e9cies. Al\u00e9m disso, a cigarrinha-do-milho \u00e9 capaz de usar a mata nativa como ref\u00fagio e acumular reservas de gordura, o que permite ela passar pelos <a href=\"https:\/\/blog.verde.ag\/pt\/culturas\/milho\/como-o-potassio-pode-auxiliar-na-diminuicao-dos-danos-da-geada-no-milho\/\">per\u00edodos mais frios do ano<\/a> em que a taxa de eclos\u00e3o de ninfas \u00e9 baixa.\u201d, explicou Lu\u00eds Eduardo Salvatico.<\/p>\n<p>Al\u00e9m das pr\u00f3prias caracter\u00edsticas da praga, Lu\u00eds Eduardo cita que um dos grandes problemas no Brasil \u00e9 o cultivo da planta hospedeira durante o ano todo em muitas regi\u00f5es do pa\u00eds, o que cria pontes verdes que proporcionam a manuten\u00e7\u00e3o das popula\u00e7\u00f5es da cigarrinha no campo.<\/p>\n<p>Entre esses fatores, tamb\u00e9m est\u00e1 inclusa a presen\u00e7a de condi\u00e7\u00f5es clim\u00e1ticas favor\u00e1veis ao desenvolvimento da praga, que potencializam a taxa de eclos\u00e3o de ninfas e n\u00famero de ovos depositados por cada f\u00eamea por dia.<\/p>\n<p>Dessa forma, Lu\u00eds Eduardo Salvatico explica que al\u00e9m do monitoramento e <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/enxofre-como-inseticida-como-ele-pode-ser-um-aliado-no-controle-de-pragas\/\">controle da praga<\/a>, tamb\u00e9m \u00e9 importante que o agricultor tamb\u00e9m valorize e potencialize a capacidade natural de defesa das plantas:<\/p>\n<p>\u201cCada vez mais \u00e9 importante buscar entender com a planta funciona, como ela reage e quais s\u00e3o os seus mecanismos de defesa, para que voc\u00ea, atrav\u00e9s da boa constru\u00e7\u00e3o do ambiente, possa tornar ela mais responsiva, mais defensiva e mais resistente \u00e0 cigarrinha-do-milho e \u00e0s doen\u00e7as transmitidas por esse vetor.\u201d<\/p>\n<p>Mas, como o agricultor pode lidar com a cigarrinha-do-milho e controlar o enfezamento do milho?<\/p>\n<div class=\"verde-content_3\" id=\"verde-1923543998\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2>Como controlar o enfezamento do milho?<\/h2>\n<p>De acordo com o agr\u00f4nomo Lu\u00eds Eduardo Salvatico, uma das pr\u00e1ticas capazes de controlar e mitigar o enfezamento do milho \u00e9 a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-a-rizobacteria-bacillus-aryabhattai-pode-contribuir-para-nutricao-de-plantas\/\">nutri\u00e7\u00e3o das plantas<\/a>. Entretanto, esse \u00e9 ainda um t\u00f3pico pouco trabalhado no campo:<\/p>\n<p>\u201cSe o complexo de enfezamentos reduz a absor\u00e7\u00e3o e assimila\u00e7\u00e3o de nutrientes e produ\u00e7\u00e3o de fotoassimilados e eu sei que existem nutrientes e elementos ben\u00e9ficos que potencializam esses processos, eu posso mitigar os problemas causados pelos enfezamentos com a boa nutri\u00e7\u00e3o das plantas. Ainda se fala muito no uso de h\u00edbridos, controle qu\u00edmico, <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/drones-no-controle-biologico-nas-lavouras\/\">controle biol\u00f3gico<\/a>, e muito pouco em nutri\u00e7\u00e3o.\u201d<\/p>\n<p>Ele explicou que existem diversos nutrientes que podem ajudar a planta a mitigar os problemas causados pelo complexo de enfezamentos sendo que, dentre eles, ele destacou o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/milho-potassio-e-enxofre\/\">pot\u00e1ssio<\/a>, o <a href=\"https:\/\/blog.verde.ag\/pt\/culturas\/milho\/qual-a-importancia-do-magnesio-na-cultura-do-milho\/\">magn\u00e9sio<\/a>, o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/boro-no-milho-importancia-manejo\/\">boro<\/a> e o <a href=\"https:\/\/blog.verde.ag\/pt\/culturas\/milho\/como-o-silicio-influencia-na-produtividade-do-milho-e-na-resistencia-a-pragas\/\">sil\u00edcio<\/a>.<\/p>\n<p>O <a href=\"https:\/\/youtu.be\/XmtNfiwTk7w\" rel=\"nofollow noopener\" target=\"_blank\">pot\u00e1ssio<\/a>, por exemplo, \u00e9 respons\u00e1vel por controlar o regime de \u00e1gua dentro da planta que, por sua vez, favorece o transporte de nutrientes dentro dos vegetais.<\/p>\n<p>Al\u00e9m disso, esse macronutriente tamb\u00e9m facilita a entrada de CO<sub>2<\/sub> para dentro da planta e proporciona o aumento do colmo do milho, o que favorece a produtividade da cultura e a resist\u00eancia das plantas ao tombamento.<\/p>\n<p>Em conclus\u00e3o, Lu\u00eds Eduardo Salvatico ressaltou que tamb\u00e9m \u00e9 preciso pensar na <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/potassio-para-milho-descubra-quando-e-quanto-aplicar\/\">dose adequada de nutrientes<\/a> quando falamos em nutri\u00e7\u00e3o de plantas. Isso porque o desequil\u00edbrio nas rela\u00e7\u00f5es nutricionais das plantas pode ter um efeito contr\u00e1rio no controle do complexo de enfezamentos e seu vetor.<\/p>\n<p>Para entender mais sobre como o pot\u00e1ssio pode contribuir no manejo da cigarrinha-do-milho, confira o v\u00eddeo do Encontro com Gigantes na \u00edntegra!<\/p>\n<p>N\u00e3o perca os pr\u00f3ximos eventos. Confira toda a programa\u00e7\u00e3o do Encontro com Gigantes e fa\u00e7a sua inscri\u00e7\u00e3o pelo link: <a href=\"https:\/\/www.encontrocomgigantes.com\/\" rel=\"nofollow noopener\" target=\"_blank\">Encontro com Gigantes<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que a cigarrinha-do-milho \u00e9 vetor de pat\u00f3genos danosos \u00e0 cultura do milho? Entenda como lidar com essa praga e evitar o enfezamento do milho!<\/p>\n","protected":false},"author":7,"featured_media":8228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[231,305,42,793,886],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/8223"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=8223"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/8223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/8228"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=8223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=8223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=8223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}