{"id":7711,"date":"2022-07-21T18:20:50","date_gmt":"2022-07-21T21:20:50","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=7711"},"modified":"2024-04-24T10:39:43","modified_gmt":"2024-04-24T13:39:43","slug":"manganes-na-banana-como-fazer-o-manejo","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/manganes-na-banana-como-fazer-o-manejo\/","title":{"rendered":"Mangan\u00eas na banana: descubra a import\u00e2ncia e como fazer o manejo"},"content":{"rendered":"<p>Segundo o pesquisador da Empresa Brasileira de Pesquisa Agropecu\u00e1ria (Embrapa), Ad\u00f4nis Moreira, o alto rendimento das bananeiras \u00e9 alcan\u00e7ado quando o solo fornece quantidades adequadas de macro e micronutrientes. \u00c9 o que ele e outros pesquisadores afirmam no estudo <em>Nutri\u00e7\u00e3o e aduba\u00e7\u00e3o de bananais cultivados na regi\u00e3o Amaz\u00f4nica<\/em>. Conhe\u00e7a, a seguir, um desses micronutrientes, o mangan\u00eas, e descubra sua import\u00e2ncia para banana e como fazer o seu manejo adequado!<\/p>\n<h2>Qual a fun\u00e7\u00e3o do mangan\u00eas na banana?<\/h2>\n<p>Para algumas regi\u00f5es do pa\u00eds, o mangan\u00eas se enquadra entre os micronutrientes com maior defici\u00eancia na cultura da banana.<\/p>\n<p>\u00c9 o caso, por exemplo, de mais de 60% dos bananais amazonenses de \u201cterra firme\u201d, que s\u00e3o acometidos pelos sintomas de defici\u00eancia de mangan\u00eas.<\/p>\n<p>\u00c9 o que observa o pesquisador Ad\u00f4nis Moreira, juntamente com seus colegas, no artigo <em>Avalia\u00e7\u00e3o do estado nutricional de bananais cultivados no Estado do Amazonas.<\/em><\/p>\n<p>A defici\u00eancia de mangan\u00eas na banana, geralmente, leva as plantas a apresentarem um amarelecimento marginal em forma de pente nas folhas mais sombreadas e opacas do ter\u00e7o m\u00e9dio da planta.<\/p>\n<p>Esse sintoma tamb\u00e9m pode estar relacionado com a queda expressiva da produ\u00e7\u00e3o e qualidade dos cachos, principalmente quando associado ao <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/o-potencial-da-rizobacteria-bacillus-aryabhattai-no-controle-de-doencas-fungicas-e-promocao-do-crescimento-das-plantas\/\">ataque do fungo<\/a>\u00a0 <em>Deigthoniella torulosa,<\/em> causador da podrid\u00e3o-negra-das-pontas.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-7715 aligncenter\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/07\/Folha-de-bananeira-com-sintomas-de-deficiencia-de-manganes..png\" alt=\"Folha de bananeira com sintomas de defici\u00eancia de mangan\u00eas.\" width=\"454\" height=\"274\" title=\"\"><\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Folha de bananeira com sintomas de defici\u00eancia de mangan\u00eas. (Fonte: MOREIRA et al, 2010) <\/em><\/p>\n<p>O aparecimento dos sintomas de defici\u00eancia de mangan\u00eas nas folhas da banana s\u00e3o um reflexo do grande ac\u00famulo desse nutriente nessa regi\u00e3o, que s\u00f3 se altera com o surgimento da <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/conheca-os-principais-os-sintomas-da-deficiencia-de-potassio-na-banana\/\">infloresc\u00eancia da banana<\/a>.<\/p>\n<p>O direcionamento do mangan\u00eas para as folhas da banana relaciona-se diretamente com as diversas fun\u00e7\u00f5es que esse nutriente desempenha nas plantas, com destaque para o processo de respira\u00e7\u00e3o e fotoss\u00edntese que \u00e9 realizado intensamente nessa regi\u00e3o.<\/p>\n<p>O <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/manganes-na-agricultura-qual-a-importancia-desse-micronutriente\/\">mangan\u00eas<\/a> \u00e9 respons\u00e1vel pela ativa\u00e7\u00e3o e modula\u00e7\u00e3o da atividade de mais de 35 enzimas envolvidas com os mais variados processos metab\u00f3licos vegetais, incluindo aquelas que participam do processo de respira\u00e7\u00e3o e fotoss\u00edntese.<\/p>\n<p>Al\u00e9m disso, esse micronutriente \u00e9 um componente estrutural de um complexo respons\u00e1vel por catalisar a rea\u00e7\u00e3o de oxida\u00e7\u00e3o da \u00e1gua na <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/qual-e-a-importancia-do-manganes-na-fotossintese\/\">fotoss\u00edntese<\/a>. Rea\u00e7\u00e3o essa que \u00e9 indispens\u00e1vel para a forma\u00e7\u00e3o do oxig\u00eanio molecular e para a reposi\u00e7\u00e3o dos el\u00e9trons que s\u00e3o perdidos pela <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/magnesio-e-clorofila-por-que-e-importante-entender-esta-relacao\/\">clorofila<\/a> na sua excita\u00e7\u00e3o.<\/p>\n<p>Outros estudos tamb\u00e9m t\u00eam correlacionado a import\u00e2ncia do mangan\u00eas na banana\u00e0 resist\u00eancia das plantas a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-a-rizobacteria-bacillus-aryabhattai-pode-ajudar-mitigar-os-efeitos-dos-estresses-bioticos-e-abioticos\/\">estresses bi\u00f3ticos<\/a>, em especial, aqueles causados por doen\u00e7as f\u00fangicas nas folhas e nas ra\u00edzes das plantas.<\/p>\n<p>Segundo o pesquisador Ronaldo Luiz Vaz de Arruda Silveira, o mangan\u00eas est\u00e1 entre os micronutrientes que mais atuam no processo de defesa das plantas contra pat\u00f3genos, uma vez que ele contribui para a s\u00edntese de compostos metab\u00f3licos secund\u00e1rios e de lignina nas plantas.<\/p>\n<p>\u00c9 o que ele descreve em seu estudo <em>Aspectos nutricionais envolvidos na ocorr\u00eancia de doen\u00e7as com \u00eanfase para a ferrugem (Puccinia psidii).<\/em><\/p>\n<p>Tendo em vista essas diferentes fun\u00e7\u00f5es desempenhadas pelo mangan\u00eas, como fazer o bom manejo desse nutriente na banana?<\/p>\n<div class=\"verde-content_3\" id=\"verde-4255667091\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2>A aduba\u00e7\u00e3o com mangan\u00eas na banana<\/h2>\n<p>O mangan\u00eas normalmente \u00e9 o segundo micronutriente mais absorvido pelas culturas agr\u00edcolas.<\/p>\n<p>No caso da bananicultura, essa tend\u00eancia tamb\u00e9m tende a se repetir e o mangan\u00eas pode inclusive chegar a ser o micronutriente mais absorvido e exportado pela banana, como demonstram alguns trabalhos realizados com a cultivar \u201cPacovan\u201d.<\/p>\n<p>As faixas de teores de mangan\u00eas adequadas para banana variam para cada cultivar. De acordo com a Embrapa, esses valores se enquadram entre:<\/p>\n<ul>\n<li>Cultivar \u201cBRS Prata Garantida\u201d (AAAB): 132-519mg\/kg;<\/li>\n<li>Cultivar \u201cThap Maeo\u201d (AAB): 116 a 259 mg\/kg;<\/li>\n<li>Cultivar \u201cCaipira\u201d (AAA): 118 a185 mg\/kg;<\/li>\n<li>Cultivar \u201cPacovan\u201d (AAB): 315 a 398 mg\/kg.<\/li>\n<\/ul>\n<p>Apesar desses valores serem inferiores aos de muitos outros nutrientes, a aduba\u00e7\u00e3o com mangan\u00eas n\u00e3o deve ser subestimada.<\/p>\n<p>Isso porque segundo a <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/como-melhorar-a-fertilidade-do-solo-e-aumentar-a-produtividade-agricola\/\">Lei de Liebig<\/a>, ou Lei do M\u00ednimo, a produtividade de uma cultura \u00e9 limitada pela aus\u00eancia ou defici\u00eancia de qualquer um dos nutrientes essenciais para as plantas, mesmo que todos os outros estejam dispon\u00edveis em <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-qual-e-a-dose-ideal-de-potassio-para-as-plantas\/\">quantidade adequadas<\/a>.<\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_45250\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/-L_0KEAQyJM?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">A Lei do M\u00ednimo foi criada por Justus von Liebig no s\u00e9culo XIV e at\u00e9 hoje segue como uma das bases mais importantes da agricultura moderna.<\/em><\/p>\n<p>Assim, \u00e9 preciso planejar e adotar as pr\u00e1ticas corretas de aduba\u00e7\u00e3o com mangan\u00eas para garantir uma boa produ\u00e7\u00e3o e qualidade dos frutos produzidos pelos bananais.<\/p>\n<p>A primeira delas consiste na realiza\u00e7\u00e3o das <a href=\"https:\/\/blog.verde.ag\/pt\/tecnicas-agricolas\/entenda-a-importancia-de-usar-os-metodos-de-analise-de-solo-adequados-no-manejo-agricola-do-potassio\/\">an\u00e1lises de solo<\/a> e <a href=\"https:\/\/blog.verde.ag\/pt\/potassio\/analise-foliar-de-potassio-importante-tecnica-para-produtividade-da-lavoura\/\">foliares<\/a> com os m\u00e9todos mais adequados, j\u00e1 que o mangan\u00eas \u00e9 um nutriente muito sens\u00edvel \u00e0s varia\u00e7\u00f5es de alguns fatores que podem afetar a interpreta\u00e7\u00e3o das an\u00e1lises.<\/p>\n<p>Segundo o estudo <em>Aduba\u00e7\u00e3o com mangan\u00eas em soja: efeitos no solo e na planta conduzido<\/em> pelo Anderson Santos Pinto, alguns extratores de mangan\u00eas alcalinos usados nas an\u00e1lises de solos, como o DTPA, podem quelatizar o mangan\u00eas presente na solu\u00e7\u00e3o de an\u00e1lise e subestimar os resultados da an\u00e1lise.<\/p>\n<p>Outra boa pr\u00e1tica consiste na ado\u00e7\u00e3o de pr\u00e1ticas de manejo que proporcionem menor <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-evitar-a-compactacao-excessiva-do-solo-atraves-de-acoes-preventivas-e-corretivas\/\">compacta\u00e7\u00e3o do solo<\/a> e melhorem a capacidade de <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-otimizar-o-uso-da-agua-no-solo-atraves-do-siltito-glauconitico\/\">reten\u00e7\u00e3o de \u00e1gua<\/a> do solo, dois outros fatores que afetam a disponibilidade de mangan\u00eas no solo.<\/p>\n<p>E, na hora de realizar a aduba\u00e7\u00e3o, o agricultor tamb\u00e9m deve se atentar \u00e0s diferentes vantagens e limita\u00e7\u00f5es de cada <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/conheca-5-fontes-de-manganes-para-plantas\/\">fonte de mangan\u00eas<\/a>.<\/p>\n<p>Aqui, de forma geral, os fertilizantes que podem apresentar uma melhor efici\u00eancia no campo e ao mesmo tempo uma melhor disponibilidade de mangan\u00eas no solo s\u00e3o as fontes de <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-quais-sao-as-vantagens-dos-fertilizantes-de-liberacao-progressiva\/\">libera\u00e7\u00e3o progressiva<\/a> e com longo <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/porque-optar-por-fertilizantes-com-efeito-residual-dos-nutrientes\/\">efeito residual<\/a> de nutrientes.<\/p>\n<h2>O bom manejo do mangan\u00eas \u00e9 muito importante para produ\u00e7\u00e3o e qualidade da banana<\/h2>\n<p>Em resumo, o mangan\u00eas desempenha fun\u00e7\u00f5es muito importantes para produ\u00e7\u00e3o e qualidade da banana, contribuindo para diversos processos metab\u00f3licos e promovendo uma melhor toler\u00e2ncia das plantas a alguns tipos estresses bi\u00f3ticos, como as doen\u00e7as f\u00fangicas.<\/p>\n<p>Assim, torna-se indispens\u00e1vel a ado\u00e7\u00e3o de pr\u00e1ticas agr\u00edcolas adequadas para o bom manejo do mangan\u00eas no solo.<\/p>\n<p>Entre tais pr\u00e1ticas, est\u00e3o inclusas a realiza\u00e7\u00e3o das an\u00e1lises do solo e foliares com os m\u00e9todos mais adequados, a ado\u00e7\u00e3o de pr\u00e1ticas que promovam a melhoria da qualidade do solo e a escolha das <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/entenda-o-que-e-o-k-forte-e-quais-beneficios-o-fertilizante-proporciona-para-a-agricultura\/\">fontes de mangan\u00eas mais adequadas<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubra a import\u00e2ncia do uso do mangan\u00eas na banana e como fazer o seu manejo adequado, fornecendo ao solo quantidades adequadas desse micronutriente para obter um alto rendimento!<\/p>\n","protected":false},"author":7,"featured_media":7712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[727,197],"tags":[436,885,103,742,741,277],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/7711"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=7711"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/7711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/7712"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=7711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=7711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=7711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}