{"id":6551,"date":"2022-04-22T19:19:28","date_gmt":"2022-04-22T22:19:28","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=6551"},"modified":"2024-03-27T11:57:05","modified_gmt":"2024-03-27T14:57:05","slug":"entenda-como-funciona-a-dinamica-de-enxofre-no-solo","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-como-funciona-a-dinamica-de-enxofre-no-solo\/","title":{"rendered":"Entenda como funciona a din\u00e2mica de enxofre no solo"},"content":{"rendered":"<p>De maneira geral, o enxofre \u00e9 o quarto nutriente mais exigido pelas culturas agr\u00edcolas. Entretanto, para que esse nutriente esteja em sua forma biodispon\u00edvel para as plantas, ele geralmente precisa passar por uma s\u00e9rie de transforma\u00e7\u00f5es no solo. Entenda a seguir como funciona a din\u00e2mica de enxofre no solo!<\/p>\n<h2><strong>O ciclo do enxofre no solo<\/strong><\/h2>\n<p>O in\u00edcio do ciclo do enxofre \u00e9 marcado pela sua entrada no solo, seja de forma natural, atrav\u00e9s da deposi\u00e7\u00e3o atmosf\u00e9rica pela \u00e1gua da chuva e solubiliza\u00e7\u00e3o de <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/conheca-os-agrominerais-silicaticos-e-a-sua-importancia-na-formacao-de-solos-agricolas\/\">minerais<\/a>, ou pela a\u00e7\u00e3o do homem, com a aplica\u00e7\u00e3o de <a href=\"https:\/\/blog.verde.ag\/pt\/tecnicas-agricolas\/beneficios-da-compostagem-para-a-producao-agricola\/\">compostos org\u00e2nicos<\/a> e fertilizantes.<\/p>\n<p>Nesse sentido, o uso de fertilizantes \u00e9 muito relevante para a atividade agr\u00edcola: s\u00f3 de enxofre elementar, um dos fertilizantes sulfatados dispon\u00edveis no mercado, s\u00e3o consumidos cerca de 1,6 milh\u00f5es de toneladas de enxofre elementar anualmente na agricultura brasileira. S\u00e3o informa\u00e7\u00f5es do Jornal Informa\u00e7\u00f5es Agron\u00f4micas 129, do International Plant Nutrition Institute (IPNI).<\/p>\n<p>Dependendo da origem do enxofre adicionado ao solo, ele pode estar em diferentes formas, denominadas estados de oxida\u00e7\u00e3o. A quantidade desses estados do enxofre no solo, geralmente, \u00e9 determinada pelas rea\u00e7\u00f5es bioqu\u00edmicas em que est\u00e3o envolvidas ou at\u00e9 mesmo pelas <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-como-aumentar-a-capacidade-do-solo-de-reter-agua-e-nutrientes\/\">condi\u00e7\u00f5es do ambiente<\/a>.<\/p>\n<p>Fertilizantes sulfatados, por exemplo, fornecem a forma mais oxidada do enxofre dentro da escala oxidativa: o sulfato (SO<sup>4<\/sup><sub>-2<\/sub>). J\u00e1 fertilizantes que cont\u00eam enxofre elementar, como o pr\u00f3prio nome sugere, fornecem a forma mais est\u00e1vel do enxofre: o <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/saiba-quais-sao-as-vantagens-do-enxofre-elementar-micronizado-para-a-sua-lavoura\/\">enxofre elementar (S<sup>0<\/sup>).<\/a><\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/blog.verde.ag\/pt\/e-book-fontes-de-enxofre-usadas-na-agricultura\/\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2023\/02\/e-book01\u2013fontes-de-enxofre-usadas-na-agricultura.jpg\" alt=\"-\" width=\"800\" height=\"1000\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/blog.verde.ag\/pt\/e-book-fontes-de-enxofre-usadas-na-agricultura\/\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2023\/02\/Banner_Ebook_Blog_1_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\t\r\n<\/div>\n<p>Al\u00e9m dessas duas formas de enxofre, tamb\u00e9m \u00e9 poss\u00edvel encontrar outros compostos sulfurados no solo, como:<\/p>\n<ul>\n<li>Di\u00f3xido de enxofre (SO<sub>2<\/sub>);<\/li>\n<li>Enxofre org\u00e2nico (R-SH);<\/li>\n<li>Tiossulfato (S<sub>2<\/sub>O<sub>3<\/sub><sup>-2<\/sup>);<\/li>\n<li>Sulfito (SO<sub>3<\/sub><sup>-2<\/sup>);<\/li>\n<li>Sulfeto (H<sub>2<\/sub>S).<\/li>\n<\/ul>\n<p>Cada um desses estados de oxida\u00e7\u00e3o do enxofre passa por diferentes transforma\u00e7\u00f5es no solo, para que consigam ser absorvidos plantas.<\/p>\n<p>A maioria do <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-como-funciona-a-mobilidade-do-enxofre-na-planta\/\">enxofre absorvido pelas plantas<\/a> se d\u00e1 com ele na forma de sulfato. Mas, as folhas das plantas tamb\u00e9m conseguem absorver pequenas quantidades de enxofre na forma do g\u00e1s di\u00f3xido de enxofre (SO<sub>2<\/sub>).<\/p>\n<p>Essas transforma\u00e7\u00f5es do enxofre s\u00e3o, em sua maioria, mediadas em sua maioria pelos microrganismos do solo.<\/p>\n<p>C\u00edntia Dutra Leal, especialista em Microbiologia Ambiental e Industrial pela Universidade Federal de Minas Gerais, explica que os microrganismos do solo, em especial as <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-as-bacterias-do-genero-thiobacillus-atuam-na-disponibilizacao-de-enxofre-para-as-plantas\/\">bact\u00e9rias,<\/a> desempenham importantes papeis tanto nas rea\u00e7\u00f5es oxidativas como nas redutivas do ciclo do enxofre.<\/p>\n<p>As rea\u00e7\u00f5es de oxida\u00e7\u00e3o biol\u00f3gica est\u00e3o presentes, por exemplo, na transforma\u00e7\u00e3o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/o-que-e-a-oxidacao-do-enxofre-elementar-e-por-que-ela-e-necessaria\/\">elementar (S<sup>0<\/sup>)<\/a> em sulfato (SO4-2) e a sua libera\u00e7\u00e3o progressiva do enxofre para a solu\u00e7\u00e3o do solo. Vale lembrar que o sulfato \u00e9 considerado a forma de enxofre mais biodispon\u00edvel para as plantas.<\/p>\n<p>Durante a oxida\u00e7\u00e3o biol\u00f3gica do enxofre, tamb\u00e9m pode haver a produ\u00e7\u00e3o de compostos intermedi\u00e1rios, como o tiossulfato (S<sub>2<\/sub>O<sub>3<\/sub><sup>-2<\/sup>). Por\u00e9m, ele \u00e9 um composto sulfurado inst\u00e1vel, principalmente em ambientes de pH mais \u00e1cido.<img decoding=\"async\" class=\"size-full wp-image-6552 aligncenter\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-2.jpg\" alt=\"Representa\u00e7\u00e3o esquem\u00e1tica do ciclo redox do enxofre, sendo o processo de oxida\u00e7\u00e3o indicados pelas setas amarelas e as redu\u00e7\u00f5es, pelas vermelhas.\" width=\"454\" height=\"419\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-2.jpg 454w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-2-300x277.jpg 300w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-2-150x138.jpg 150w\" sizes=\"(max-width: 454px) 100vw, 454px\" title=\"\"><\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Representa\u00e7\u00e3o esquem\u00e1tica do ciclo redox do enxofre, sendo o processo de oxida\u00e7\u00e3o indicados pelas setas amarelas e as redu\u00e7\u00f5es, pelas vermelhas.<\/em><\/p>\n<p>Mas, se j\u00e1 existem fertilizantes que liberam o enxofre no solo diretamente absorvida pelas plantas, por que optar por <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/conheca-as-principais-fontes-de-enxofre-na-adubacao-e-quais-sao-suas-vantagens\/\">fontes de enxofre<\/a> que t\u00eam de passar por diferentes etapas de transforma\u00e7\u00e3o?<\/p>\n<p>Fertilizantes que cont\u00eam o enxofre na forma de sulfato, diferentemente dos que cont\u00eam enxofre elementar, n\u00e3o conseguem manter um equil\u00edbrio entre a libera\u00e7\u00e3o de nutrientes e a taxa de absor\u00e7\u00e3o do enxofre pelas plantas. Isso porque todo o conte\u00fado de nutrientes come\u00e7a a ser liberado logo ap\u00f3s a sua aplica\u00e7\u00e3o.<\/p>\n<p>O resultado negativo desse desequil\u00edbrio \u00e9 a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/lixiviacao-de-nutrientes-por-que-o-potassio-possui-o-maior-risco-de-perdas\/\">lixivia\u00e7\u00e3o dos nutrientes<\/a>, que pode gerar problemas econ\u00f4micos e ambientais para o agricultor. S\u00e3o consequ\u00eancias como a contamina\u00e7\u00e3o dos len\u00e7\u00f3is fre\u00e1ticos e a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/salinidade-do-solo-uma-ameaca-a-produtividade-agricola\/\">saliniza\u00e7\u00e3o<\/a> das \u00e1reas de cultivo, pela constante necessidade de reaplica\u00e7\u00e3o de insumos com elevado \u00edndice salino.<\/p>\n<p>Como, ent\u00e3o, alcan\u00e7ar o n\u00edvel ideal de enxofre no solo?<\/p>\n<div class=\"verde-content_3\" id=\"verde-1624025423\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2><strong>O n\u00edvel ideal de enxofre no solo<\/strong><\/h2>\n<p>Segundo a Embrapa, o n\u00edvel ideal de enxofre no solo pode ser alcan\u00e7ado analisando a sua disponibilidade de acordo com a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/composicao-do-solo-por-que-e-importante-conhecer-seu-solo\/\">textura do solo<\/a> e em duas profundidades, 0 a 20 cm e 20 a 40 cm. Essa recomenda\u00e7\u00e3o parte da tend\u00eancia que o enxofre tem para se acumular na camada subsuperficial do solo, principalmente quando ele \u00e9 fornecido na forma de sulfato.<\/p>\n<p>Apesar de ainda existirem poucas informa\u00e7\u00f5es relativas ao n\u00edvel cr\u00edtico de enxofre no solo para algumas culturas, que \u00e9 aquele ponto em que o teor de um nutriente no solo atinge 90% da produ\u00e7\u00e3o relativa da cultura, os valores tendem a ser menores nas camadas superficiais e maiores para as camadas subsuperficiais.<\/p>\n<p>Tamb\u00e9m \u00e9 importante se atentar no momento da escolha do m\u00e9todo de an\u00e1lise das amostras de solo. Isso porque \u00e9 preciso que sejam levados em considera\u00e7\u00e3o n\u00e3o somente os nutrientes presentes na solu\u00e7\u00e3o do solo, mas tamb\u00e9m daqueles presentes na fase s\u00f3lida do solo que conseguem passar para a solu\u00e7\u00e3o, conhecidos como\u00a0<a tabindex=\"-1\" title=\"https:\/\/blog.verde.ag\/pt\/tecnicas-agricolas\/como-e-feita-a-analise-de-enxofre-labil-no-solo\/\" href=\"https:\/\/blog.verde.ag\/pt\/tecnicas-agricolas\/como-e-feita-a-analise-de-enxofre-labil-no-solo\/\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Link enxofre l\u00e1bil\">enxofre l\u00e1bil<\/a>.<\/p>\n<p>Vale destacar que, embora n\u00e3o seja\u00a0poss\u00edvel estipular uma dose de enxofre fixa para todas as realidades,\u00a0o agricultor deve ter em mente que:\u00a0a solubilidade em \u00e1gua e a\u00a0<a tabindex=\"-1\" title=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/qual-a-diferenca-entre-solubilidade-em-agua-e-disponibilidade-de-nutrientes\/\" href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/qual-a-diferenca-entre-solubilidade-em-agua-e-disponibilidade-de-nutrientes\/\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Link disponibilidade de nutrientes\">disponibilidade de nutrientes<\/a>\u00a0devem ser conceitos tratados de forma diferente na hora da escolha dos fertilizantes para a lavoura.<\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_52300\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/FJBKLwuv-sI?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Na hora de escolher fertilizantes para a lavoura, \u00e9 preciso tratar de forma diferente os conceitos de solubilidade em \u00e1gua e disponibilidade de nutrientes. <\/em><\/p>\n<p>Dessa forma, dentre as diferentes caracter\u00edsticas que podem ser consideradas no momento da escolha da fonte de enxofre ideal, \u00e9 recomendado observar principalmente caracter\u00edsticas como:<\/p>\n<ul>\n<li>A forma de <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/quais-sao-as-diferencas-entre-fertilizante-de-liberacao-gradual-e-imediata\/\">libera\u00e7\u00e3o do fertilizante<\/a>;<\/li>\n<li>O <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/descubra-as-diferencas-entre-o-enxofre-pastilhado-e-o-enxofre-micronizado\/\">tamanho da part\u00edcula<\/a>;<\/li>\n<li>O <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/porque-optar-por-fertilizantes-com-efeito-residual-dos-nutrientes\/\">efeito residual<\/a>;<\/li>\n<li>O <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/como-combater-a-salinizacao-dos-solos-e-aumentar-a-produtividade-agricola\/\">\u00edndice salino<\/a>.<\/li>\n<li>O <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/qual-e-a-fonte-mais-barata-de-enxofre-para-a-agricultura\/\">pre\u00e7o<\/a>.<\/li>\n<\/ul>\n<h2><strong>Entender sobre a din\u00e2mica do enxofre no solo pode auxiliar no manejo da fertilidade do solo<\/strong><\/h2>\n<p>Em resumo, entender mais sobre a din\u00e2mica do enxofre no solo pode tornar o manejo da <a href=\"https:\/\/blog.verde.ag\/pt\/consultores-do-agro\/como-entender-sobre-a-fertilidade-do-solo-ajuda-na-escolha-dos-fertilizantes\/\">fertilidade do solo<\/a> mais assertivo e eficiente.<\/p>\n<p>Para isso, o agricultor deve sempre se atentar no momento de an\u00e1lise do solo e da escolha de fertilizantes, buscando optar por <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/entenda-o-que-e-o-baks-e-as-suas-vantagens-para-uma-nova-agricultura\/\">fontes de enxofre<\/a> com um maior efeito residual e a libera\u00e7\u00e3o progressiva dos nutrientes para suprir as necessidades nutricionais das lavouras ao longo das diferentes safras agr\u00edcolas!<\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-MOBILE\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Mobile.jpg\" alt=\"-\" width=\"800\" height=\"400\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-DESKTOP\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>Descubra como funciona a din\u00e2mica de enxofre no solo e conhe\u00e7a quais transforma\u00e7\u00f5es o enxofre passa at\u00e9 que ele esteja biodispon\u00edvel para as plantas.  <\/p>\n","protected":false},"author":7,"featured_media":6553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[197],"tags":[620,621,253,885],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/6551"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=6551"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/6551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/6553"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=6551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=6551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=6551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}