{"id":6461,"date":"2022-04-13T18:17:47","date_gmt":"2022-04-13T21:17:47","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=6461"},"modified":"2024-03-27T11:51:30","modified_gmt":"2024-03-27T14:51:30","slug":"qual-o-papel-dos-microrganismos-no-ciclo-do-enxofre","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/qual-o-papel-dos-microrganismos-no-ciclo-do-enxofre\/","title":{"rendered":"Qual o papel dos microrganismos no ciclo do enxofre?"},"content":{"rendered":"<p>Na natureza, o enxofre apresenta diversas formas qu\u00edmicas por sofrer uma s\u00e9rie de transforma\u00e7\u00f5es. Transforma\u00e7\u00f5es essas que, no solo, s\u00e3o mediadas principalmente pelos microrganismos. Entenda mais sobre o papel dos microrganismos no ciclo do enxofre e a sua import\u00e2ncia no contexto agr\u00edcola!<\/p>\n<h2><strong>Onde ocorre o ciclo do enxofre?<\/strong><\/h2>\n<p>O ciclo de enxofre ocorre tanto na atmosfera quanto no solo, mas \u00e9 nesse \u00faltimo ambiente que a maioria das transforma\u00e7\u00f5es pelas quais esse elemento passa se concentram.<\/p>\n<p>Devido ao fato de que existe um movimento c\u00edclico do enxofre entre os organismos vivos e o <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/conheca-os-agrominerais-silicaticos-e-a-sua-importancia-na-formacao-de-solos-agricolas\/\">ambiente geol\u00f3gico<\/a>, o ciclo do enxofre tamb\u00e9m pode ser conhecido como ciclo biogeoqu\u00edmico.<img decoding=\"async\" class=\"size-full wp-image-6462 aligncenter\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-do-ciclo-do-enxofre-na-agricultura..jpg\" alt=\"Representa\u00e7\u00e3o do ciclo do enxofre na agricultura.\" width=\"567\" height=\"368\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-do-ciclo-do-enxofre-na-agricultura..jpg 567w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-do-ciclo-do-enxofre-na-agricultura.-300x195.jpg 300w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-do-ciclo-do-enxofre-na-agricultura.-150x97.jpg 150w\" sizes=\"(max-width: 567px) 100vw, 567px\" title=\"\"><\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Representa\u00e7\u00e3o do ciclo do enxofre na agricultura. (Fonte: PAULETTI, UFPR)<\/em><\/p>\n<p>O enxofre pode chegar at\u00e9 o solo por diferentes meios, como as adi\u00e7\u00f5es atmosf\u00e9ricas ou o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/conheca-as-principais-fontes-de-enxofre-na-adubacao-e-quais-sao-suas-vantagens\/\">uso de fertilizantes<\/a>. Entretanto, dependendo da sua origem, o enxofre se encontra em diferentes formas, denominadas estados de oxida\u00e7\u00e3o.<\/p>\n<p>Fertilizantes sulfatados, por exemplo, fornecem a forma mais oxidada do enxofre dentro da escala oxidativa: o sulfato (SO<sub>4<\/sub><sup>-2<\/sup>). J\u00e1 fertilizantes que cont\u00eam enxofre elementar, fornecem a forma mais est\u00e1vel do enxofre: o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/o-que-e-a-oxidacao-do-enxofre-elementar-e-por-que-ela-e-necessaria\/\">enxofre elementar (S<sup>0<\/sup>)<\/a>.<\/p>\n<p>Al\u00e9m dessas duas formas de enxofre, tamb\u00e9m \u00e9 poss\u00edvel encontrar outros compostos sulfurados no solo dependendo do seu estado de oxida\u00e7\u00e3o. Al\u00e9m do sulfato (SO<sub>4<\/sub><sup>-2<\/sup>) e do enxofre elementar (S<sup>0<\/sup>), tamb\u00e9m \u00e9 poss\u00edvel encontrar no solo o enxofre sob a forma de:<\/p>\n<ul>\n<li>Di\u00f3xido de enxofre (SO<sub>2<\/sub>);<\/li>\n<li>Enxofre org\u00e2nico (R-SH);<\/li>\n<li>Tiossulfato (S<sub>2<\/sub>O<sub>3<\/sub><sup>-2<\/sup>);<\/li>\n<li>Sulfito (SO<sub>3<\/sub><sup>-2<\/sup>);<\/li>\n<li>Sulfeto (H<sub>2<\/sub>S).<\/li>\n<\/ul>\n<p>Vale destacar que a quantidade desses estados do enxofre no solo \u00e9 determinada pelas rea\u00e7\u00f5es bioqu\u00edmicas em que est\u00e3o envolvidas ou at\u00e9 mesmo pelas <a href=\"https:\/\/blog.verde.ag\/pt\/consultores-do-agro\/entenda-como-condicoes-de-estresse-afetam-as-plantas-e-como-lidar-com-elas\/\">condi\u00e7\u00f5es do ambiente<\/a>, que podem favorecer ou n\u00e3o essas transforma\u00e7\u00f5es.<\/p>\n<p>Mas, como ocorre a transi\u00e7\u00e3o dessas diferentes formas de enxofre para que ele consiga ser absorvido pelas plantas, que s\u00e3o consideradas um dos principais componentes intermedi\u00e1rios do ciclo do enxofre?<\/p>\n<div class=\"verde-content_3\" id=\"verde-3671965212\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2><strong>O papel dos microrganismos entre os fatores que interferem no ciclo do enxofre<\/strong><\/h2>\n<p>Os <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/7-beneficios-dos-microrganismos-no-solo\/\">microrganismos do solo<\/a> figuram entre os principais fatores que interferem positivamente no ciclo do enxofre, sendo respons\u00e1veis por mediar as principais transforma\u00e7\u00f5es desse elemento no solo.<\/p>\n<p>No estudo <em>Aplica\u00e7\u00e3o de bact\u00e9rias do ciclo do enxofre no tratamento de efluentes e recupera\u00e7\u00e3o de enxofre elementar, <\/em>C\u00edntia Dutra Leal explica que as <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-a-rizobacteria-bacillus-aryabhattai-pode-contribuir-para-nutricao-de-plantas\/\">bact\u00e9rias<\/a> desempenham importantes papeis tanto nas rea\u00e7\u00f5es oxidativas como nas redutivas do ciclo do enxofre.<\/p>\n<p>Segundo a pesquisadora, enquanto as bact\u00e9rias que oxidam sulfeto e enxofre produzem sulfato, as bact\u00e9rias redutoras de sulfato consomem o sulfato e produzem o sulfeto de hidrog\u00eanio.<\/p>\n<p>Assim, o enxofre do solo se encontra em uma constante e complexa transi\u00e7\u00e3o entre seus diferentes estados de oxida\u00e7\u00e3o.<img decoding=\"async\" class=\"size-full wp-image-6463 aligncenter\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-1.jpg\" alt=\"Representa\u00e7\u00e3o esquem\u00e1tica do ciclo redox do enxofre, sendo o processo de oxida\u00e7\u00e3o indicados pelas setas amarelas e as redu\u00e7\u00f5es, pelas vermelhas.\" width=\"453\" height=\"418\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-1.jpg 453w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-1-300x277.jpg 300w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/04\/Representacao-esquematica-do-ciclo-redox-do-enxofre-sendo-o-processo-de-oxidacao-indicados-pelas-setas-amarelas-e-as-reducoes-pelas-vermelhas.-1-150x138.jpg 150w\" sizes=\"(max-width: 453px) 100vw, 453px\" title=\"\"><\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Representa\u00e7\u00e3o esquem\u00e1tica do ciclo redox do enxofre, sendo o processo de oxida\u00e7\u00e3o indicados pelas setas amarelas e as redu\u00e7\u00f5es, pelas vermelhas.<\/em><\/p>\n<p>De acordo com os pesquisadores Murali Krishna e Ligy Philip, autores do artigo <em>Thiobacillus denitrificans immobilized biotrickling filter for NO<sub>2<\/sub> removal, <\/em>um dos principais grupos de microrganismos que realizam essas transforma\u00e7\u00f5es do enxofre no solo \u00e9 o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-as-bacterias-do-genero-thiobacillus-atuam-na-disponibilizacao-de-enxofre-para-as-plantas\/\">g\u00eanero <em>Thiobacillus<\/em><\/a><em>. <\/em><\/p>\n<p>O g\u00eanero <em>Thiobacillus,<\/em> juntamente com os g\u00eaneros<em> Sulfolobus e Sulfobacillus, <\/em>s\u00e3o consideradas bact\u00e9rias quimiotr\u00f3ficas e participam da transforma\u00e7\u00e3o do enxofre em ambientes com uma maior disponibilidade de oxig\u00eanio.<\/p>\n<p>Caso a disponibilidade de oxig\u00eanio no solo seja muito baixa, quem entram em a\u00e7\u00e3o s\u00e3o bact\u00e9rias fototr\u00f3ficas dos g\u00eaneros<em> Chlorobium e Cromatium.<\/em><\/p>\n<p>Entretanto, a condi\u00e7\u00e3o de <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-evitar-a-compactacao-excessiva-do-solo-atraves-de-acoes-preventivas-e-corretivas\/\">aera\u00e7\u00e3o do solo<\/a> e a presen\u00e7a desses microrganismos n\u00e3o s\u00e3o os \u00fanicos fatores que podem interferir no processo de oxida\u00e7\u00e3o biol\u00f3gico do enxofre. Processo esse que tamb\u00e9m pode sofrer a influ\u00eancia:<\/p>\n<ul>\n<li>Da superf\u00edcie espec\u00edfica da fonte de enxofre;<\/li>\n<li>Da temperatura e <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-como-aumentar-a-capacidade-do-solo-de-reter-agua-e-nutrientes\/\">umidade do solo<\/a>;<\/li>\n<li>Do teor de mat\u00e9ria org\u00e2nica;<\/li>\n<li>Do pH e da <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/composicao-do-solo-por-que-e-importante-conhecer-seu-solo\/\">textura do solo<\/a>.<\/li>\n<\/ul>\n<p>\u00c9 o que explicam Rafael Jos\u00e9 Oliveira e outros pesquisadores, no artigo <em>Elementary sulfur oxidation in different sources and doses of fertilizers.<\/em><\/p>\n<p>Os pesquisadores citam, por exemplo, que quanto maior o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/composicao-do-solo-por-que-e-importante-conhecer-seu-solo\/\">teor de argila<\/a> e <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/o-manejo-agricola-como-ferramenta-para-aumentar-a-materia-organica-do-solo\/\">mat\u00e9ria org\u00e2nica<\/a> do solo, maior a tend\u00eancia de oxida\u00e7\u00e3o.<\/p>\n<p>Por fim, o processo de oxida\u00e7\u00e3o realizado pelos microrganismos do solo vai culminar na forma\u00e7\u00e3o do sulfato (SO<sub>4<\/sub><sup>-2<\/sup>), uma das formas de enxofre mais <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/qual-a-diferenca-entre-solubilidade-em-agua-e-disponibilidade-de-nutrientes\/\">biodispon\u00edveis<\/a> para as plantas.<\/p>\n<p>Mas, porque depender do processo de oxida\u00e7\u00e3o de enxofre realizado pelos microrganismos, se existem fertilizantes que podem fornecer o enxofre diretamente na forma absorvida por elas?<\/p>\n<h2><strong>As fontes de enxofre para as plantas<\/strong><\/h2>\n<p>Apesar dos <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-as-vantagens-e-desvantagens-do-sulfato-de-potassio\/\">fertilizantes sulfatados<\/a> normalmente n\u00e3o precisarem passar por nenhuma transforma\u00e7\u00e3o no solo para serem absorvidos pelas plantas, existe uma grande limita\u00e7\u00e3o no seu uso: a perda de nutrientes.<\/p>\n<p>Como a libera\u00e7\u00e3o do sulfato desses fertilizantes n\u00e3o acompanha a taxa de absor\u00e7\u00e3o do enxofre pelas plantas, pode existir perdas significativas do enxofre pelo processo de <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/lixiviacao-de-nutrientes-por-que-o-potassio-possui-o-maior-risco-de-perdas\/\">lixivia\u00e7\u00e3o<\/a>.<\/p>\n<p>Essas perdas, al\u00e9m de levarem a preju\u00edzos econ\u00f4micos para o agricultor, podem acarretar em s\u00e9rios problemas ambientais como a contamina\u00e7\u00e3o dos len\u00e7\u00f3is fre\u00e1ticos da regi\u00e3o.<\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/blog.verde.ag\/pt\/e-book-fontes-de-enxofre-usadas-na-agricultura\/\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2023\/02\/e-book01\u2013fontes-de-enxofre-usadas-na-agricultura.jpg\" alt=\"-\" width=\"800\" height=\"1000\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/blog.verde.ag\/pt\/e-book-fontes-de-enxofre-usadas-na-agricultura\/\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2023\/02\/Banner_Ebook_Blog_1_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\t\r\n<\/div>\n<p>Al\u00e9m disso, tamb\u00e9m existe a possibilidade de <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-a-glauconita-pode-reduzir-os-efeitos-negativos-da-salinizacao-do-solo\/\">saliniza\u00e7\u00e3o<\/a> das \u00e1reas de plantio, j\u00e1 que surge a necessidade da constante reaplica\u00e7\u00e3o de insumos que geralmente apresentam um alto <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/salinidade-do-solo-uma-ameaca-a-produtividade-agricola\/\">\u00edndice salino<\/a>.<\/p>\n<p>Uma das principais alternativas para se evitar as <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/porque-o-desempenho-do-sulfato-de-potassio-na-agricultura-aponta-algumas-limitacoes-desse-fertilizante\/\">limita\u00e7\u00f5es dos fertilizantes sulfatados<\/a> e aproveitar o potencial dos microrganismos do solo \u00e9 com o uso de fertilizantes que contenham enxofre elementar, preferencialmente na sua <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/saiba-quais-sao-as-vantagens-do-enxofre-elementar-micronizado-para-a-sua-lavoura\/\">forma micronizada.<\/a><\/p>\n<p>Quando os microrganismos entram em contato com o enxofre elementar, eles conseguem promover a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-quais-sao-as-vantagens-dos-fertilizantes-de-liberacao-progressiva\/\">libera\u00e7\u00e3o progressiva<\/a> do nutriente para as plantas atrav\u00e9s do processo de oxida\u00e7\u00e3o biol\u00f3gica. Sendo que, quanto menor for a part\u00edcula do produto, mais eficiente se dar\u00e1 esse processo.<\/p>\n<p>Assim, as plantas conseguem ter acesso ao enxofre ao longo do seu ciclo produtivo e o agricultor recebe benef\u00edcios tanto econ\u00f4micos quanto ambientais. Isso porque ele reduzir\u00e1 o n\u00famero de aplica\u00e7\u00f5es na lavoura e n\u00e3o estar\u00e1 sujeito aos problemas relacionados \u00e0 lixivia\u00e7\u00e3o de nutrientes.<\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_47106\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/GHQ3T8FotsE?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">O uso do enxofre elementar micronizado traz muitos benef\u00edcios para a lavoura.<\/em><\/p>\n<h2><strong>O uso do enxofre elementar micronizado favorece a nutri\u00e7\u00e3o das plantas e a sustentabilidade econ\u00f4mica e ambiental do agricultor<\/strong><\/h2>\n<p>Em resumo, os microrganismos do solo desempenham um papel muito importante no ciclo do enxofre, tornando esse nutriente dispon\u00edvel para as plantas.<\/p>\n<p>Entender esse ciclo \u00e9 importante para que o agricultor fa\u00e7a escolhas mais assertivas na hora de fazer o manejo de enxofre da lavoura.<\/p>\n<p>Escolhas que levem, por exemplo, ao melhor aproveitamento do potencial dos fertilizantes. O que pode ser feito com o uso de fertilizantes que contenham <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/entenda-o-que-e-o-baks-e-as-suas-vantagens-para-uma-nova-agricultura\/\">enxofre elementar micronizado<\/a>, que favorece tanto a nutri\u00e7\u00e3o das plantas quanto a sustentabilidade econ\u00f4mica e ambiental do agricultor!<\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-MOBILE\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Mobile.jpg\" alt=\"-\" width=\"800\" height=\"400\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-DESKTOP\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>Entenda qual o papel dos microrganismos no ciclo do enxofre e como o agricultor pode usar isso para fazer escolhas mais assertivas no contexto agr\u00edcola.<\/p>\n","protected":false},"author":7,"featured_media":6464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[197],"tags":[608,885,268,224],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/6461"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=6461"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/6461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/6464"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=6461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=6461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=6461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}