{"id":5543,"date":"2022-01-28T18:41:55","date_gmt":"2022-01-28T21:41:55","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=5543"},"modified":"2024-03-22T12:16:22","modified_gmt":"2024-03-22T15:16:22","slug":"silicio-na-cana-conheca-os-beneficios","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/culturas\/cana\/silicio-na-cana-conheca-os-beneficios\/","title":{"rendered":"Sil\u00edcio na cana: conhe\u00e7a os benef\u00edcios"},"content":{"rendered":"<p>O sil\u00edcio \u00e9 considerado como o elemento mais absorvido e acumulado pela cana, podendo acumular quase 400 kg\/ha na parte a\u00e9rea, dependendo da cultivar.\u00a0 Esse dado, apresentado por G. Samuels no artigo <em>Silicon and sugar,<\/em> revela que a alta demanda de sil\u00edcio na cana indica que ele desempenha diversas fun\u00e7\u00f5es importantes para a cultura. Conhe\u00e7a os benef\u00edcios do sil\u00edcio na cana!<\/p>\n<h2><strong>Quais s\u00e3o os principais benef\u00edcios da aduba\u00e7\u00e3o silicatada?<\/strong><\/h2>\n<p>O <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/qual-e-a-importancia-do-silicio-na-agricultura\/\">sil\u00edcio<\/a> (Si) \u00e9 considerado pela comunidade cient\u00edfica desde 2015 como um elemento ben\u00e9fico, porque a aduba\u00e7\u00e3o silicatada \u00e9 capaz de oferecer <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/quais-sao-os-beneficios-do-uso-do-silicio-nas-plantas\/\">diversos benef\u00edcios<\/a> para as culturas agr\u00edcolas.<\/p>\n<p>Tais benef\u00edcios incluem a indu\u00e7\u00e3o da resist\u00eancia das plantas a pragas e doen\u00e7as e o aumento da produtividade das culturas.<\/p>\n<p>Estima-se que sete das dez principais culturas mais produzidas no mundo s\u00e3o acumuladoras de sil\u00edcio, estando entre elas o <a href=\"https:\/\/blog.verde.ag\/pt\/culturas\/milho\/silicio-no-milho-qual-a-importancia-e-a-melhor-maneira-de-adubar\/\">milho<\/a>, o arroz, o trigo e a cana-de-a\u00e7\u00facar. \u00c9 o que apresentam Flore Guntzer e outros pesquisadores no artigo <em>Benefits of plant silicon for crops: A review.<\/em><\/p>\n<p>Na parte \u00e1rea das plantas, quando comparado ao ac\u00famulo de nutrientes como o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-a-adubacao-potassica-pode-influenciar-a-produtividade-da-cana\/\">pot\u00e1ssio,<\/a> o nitrog\u00eanio e o f\u00f3sforo, o ac\u00famulo de sil\u00edcio na cana pode chegar a ser mais de duas vezes maior.<\/p>\n<p>Contudo, esse ac\u00famulo depende da disponibilidade desse elemento no solo e de alguns outros fatores.<\/p>\n<p>No caso dos solos tropicais, esses teores de sil\u00edcio no solo geralmente s\u00e3o muito baixos, porque eles s\u00e3o altamente intemperizados e t\u00eam uma presen\u00e7a quase inexistente de <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/conheca-os-agrominerais-silicaticos-e-a-sua-importancia-na-formacao-de-solos-agricolas\/\">minerais prim\u00e1rios que cont\u00eam sil\u00edcio<\/a>.<\/p>\n<p>Nesse sentido, a aduba\u00e7\u00e3o silicatada \u00e9 indispens\u00e1vel para o ac\u00famulo de sil\u00edcio na cana e a express\u00e3o de seus benef\u00edcios para as plantas. Dentre eles, os estudos acerca do assunto j\u00e1 destacaram os seguintes benef\u00edcios do sil\u00edcio para a cultura:<\/p>\n<h3><strong>1. Aumento da produtividade<\/strong><\/h3>\n<p>A aplica\u00e7\u00e3o de sil\u00edcio na cultura da cana-de-a\u00e7\u00facar tem demonstrado resultados concisos para o aumento da produtividade das lavouras de cana-planta e cana-soca, no Brasil e tamb\u00e9m outros pa\u00edses.<\/p>\n<p>No estudo <em>Uso de silicatos em cana-de-a\u00e7\u00facar<\/em>, Jos\u00e9 Luiz Dematt\u00ea e outros pesquisadores realizaram ensaios com aduba\u00e7\u00e3o silicatada em tr\u00eas diferentes usinas de cana no estado de S\u00e3o Paulo.<\/p>\n<p>Os resultados mostraram que a aplica\u00e7\u00e3o do nutriente nas lavouras gerou aumento da produtividade em at\u00e9 15 toneladas por hectare.<\/p>\n<p>Tamb\u00e9m no estado de S\u00e3o Paulo, o pesquisador Dorival Pires de Arruda conseguiu avaliar os teores de sil\u00edcio com 8 diferentes <a href=\"https:\/\/blog.verde.ag\/pt\/tecnicas-agricolas\/conheca-os-3-extratores-de-potassio-mais-utilizados-no-brasil-e-suas-limitacoes\/\">extratores<\/a>, e correlacion\u00e1-los \u00e0 produtividade da cultura da cana. Resultados que foram explorados no estudo <em>Avalia\u00e7\u00e3o de extratores qu\u00edmicos na determina\u00e7\u00e3o de sil\u00edcio dispon\u00edvel em solos cultivados com cana-de-a\u00e7\u00facar.<\/em><img decoding=\"async\" class=\"size-full wp-image-5550 aligncenter\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/01\/Imagem2-2.jpg\" alt=\"Correla\u00e7\u00e3o entre os teores de sil\u00edcio no solo (mg.dm-3) obtidos com o extrator \u00e1cido ac\u00e9tico e a produtividade da cana, em solos de textura argilosa (esquerda), m\u00e9dia (direita) e arenosa (em baixo). (Fonte: ARRUDA, 2009)\" width=\"581\" height=\"374\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/01\/Imagem2-2.jpg 581w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2022\/01\/Imagem2-2-300x193.jpg 300w\" sizes=\"(max-width: 581px) 100vw, 581px\" title=\"\"><\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Correla\u00e7\u00e3o entre os teores de sil\u00edcio no solo (mg.dm<sup>-3<\/sup>) obtidos com o extrator \u00e1cido ac\u00e9tico e a produtividade da cana, em solos de textura argilosa (esquerda), m\u00e9dia (direita) e arenosa (em baixo). (Fonte: ARRUDA, 2009)<\/em><\/p>\n<p>Mas, como o sil\u00edcio pode aumentar a produtividade da cana-de-a\u00e7\u00facar?<\/p>\n<p>Pesquisadores como o Dr. Lawrence Datnoff, no estudo <em>Silicon nutrition and sugarcane production: A review<\/em>, associam o aumento da produtividade da cana-de-a\u00e7\u00facar com os efeitos positivos que o uso da aduba\u00e7\u00e3o silicatada promove, como:<\/p>\n<ul>\n<li>Redu\u00e7\u00e3o dos efeitos da toxicidade do alum\u00ednio, mangan\u00eas e ferro;<\/li>\n<li><a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/como-o-teor-de-fosforo-no-solo-e-influenciado-pelas-doses-de-silicio\/\">Aumento da disponibilidade de f\u00f3sforo<\/a>;<\/li>\n<li>Maior rigidez das folhas e dos colmos;<\/li>\n<li>Aumento da efici\u00eancia h\u00eddrica vegetal;<\/li>\n<li>Redu\u00e7\u00e3o do acamamento.<\/li>\n<\/ul>\n<p>Outros efeitos secund\u00e1rios que tamb\u00e9m favorecem a produtividade, como o tempo de matura\u00e7\u00e3o e teores de s\u00f3lidos sol\u00faveis no caldo da cana, v\u00eam sendo favorecidos pela aduba\u00e7\u00e3o silicatada adequada.<\/p>\n<h3><strong>2. Indu\u00e7\u00e3o de resist\u00eancia das plantas a pragas e doen\u00e7as<\/strong><\/h3>\n<p>Dentro do <a href=\"https:\/\/blog.verde.ag\/pt\/manejo-de-pragas-e-doencas\/como-o-silicio-ajuda-no-combate-a-pragas-e-doencas-das-plantas\/\">manejo integrado de pragas e doen\u00e7as<\/a>, o sil\u00edcio tamb\u00e9m pode atuar na indu\u00e7\u00e3o de resist\u00eancia das plantas, atrav\u00e9s da ativa\u00e7\u00e3o ou desenvolvimento de \u00a0mecanismos f\u00edsicos, qu\u00edmicos e fisiol\u00f3gicos.<\/p>\n<p>Quando o sil\u00edcio \u00e9 translocado das ra\u00edzes para as partes superiores da cana, como o caule e as folhas, ele \u00e9 depositado sob a forma de s\u00edlica amorfa nas c\u00e9lulas da epiderme vegetal. Essa deposi\u00e7\u00e3o cria uma barreira f\u00edsica que:<\/p>\n<ul>\n<li>Reduz a penetra\u00e7\u00e3o dos fungos patog\u00eanicos;<\/li>\n<li>Dificulta o processo de alimenta\u00e7\u00e3o das pragas, como as <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/a-importancia-do-silicio-no-manejo-integrado-de-lagartas\/\">lagartas<\/a>;<\/li>\n<li>Diminui ou atrasa a velocidade dos danos das pragas, otimizando a atua\u00e7\u00e3o de <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/como-os-agentes-de-controle-biologico-estao-presentes-na-agricultura-de-alta-performance\/\">inimigos naturais<\/a> e outros agentes de controle.<\/li>\n<\/ul>\n<p>Al\u00e9m disso, estudos sugerem que o sil\u00edcio aumenta o metabolismo secund\u00e1rio das plantas e eleva a concentra\u00e7\u00e3o de compostos de defesa, como fitoalexinas, fen\u00f3is e fenilpropan\u00f3ides.<\/p>\n<p>O pesquisador da Embrapa Anderson Carlos Marafon, em entrevista ao Jornal Dia de Campo, citou algumas das <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/proteja-sua-lavoura-de-cana-de-acucar-contra-pragas-com-silicio\/\">principais pragas<\/a> e doen\u00e7as que podem ser diminu\u00eddas com o ac\u00famulo de sil\u00edcio na cana, como:<\/p>\n<ul>\n<li>Cigarrinhas da folha (<em>Mahanarva posticata<\/em>) e das ra\u00edzes (<em>Mahanarva fimbriolata<\/em>);<\/li>\n<li>Ferrugem da cana-de-a\u00e7\u00facar (<em>Puccinia melanocephala<\/em>);<\/li>\n<li>Mancha anelar (<em>Leptosphaeria sacchari<\/em>);<\/li>\n<li>Broca-da-cana (<em>Diatraea saccharalis<\/em>).<\/li>\n<\/ul>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_68642\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/hxVH4c85o44?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Pr\u00e1ticas essenciais para usar o sil\u00edcio no controle de pragas da cana-de-a\u00e7\u00facar.<\/em><\/p>\n<h3><strong>3. Melhoria da resist\u00eancia das plantas a condi\u00e7\u00f5es de estresses abi\u00f3ticos<\/strong><\/h3>\n<p>Quando as condi\u00e7\u00f5es ambientais n\u00e3o s\u00e3o favor\u00e1veis para o desenvolvimento das plantas, seja pelo excesso ou defici\u00eancia de fatores como \u00e1gua, luz ou temperatura, os vegetais come\u00e7am entrar em um estado de <a href=\"https:\/\/blog.verde.ag\/pt\/consultores-do-agro\/entenda-como-condicoes-de-estresse-afetam-as-plantas-e-como-lidar-com-elas\/\">estresse<\/a>.<\/p>\n<p>Nessas condi\u00e7\u00f5es, a produtividade das lavouras pode ser muito afetada. M\u00e1rio Campos, presidente da Associa\u00e7\u00e3o das Ind\u00fastrias Sucroenerg\u00e9ticas de Minas Gerais (Siamig), cita a seca como uma das principais causas na queda da produ\u00e7\u00e3o de cana-de-a\u00e7\u00facar 2021\/22 frente \u00e0 safra anterior.<\/p>\n<p>Uma das solu\u00e7\u00f5es para esse problema pode ser encontrada com o uso de sil\u00edcio na cana.<\/p>\n<p>Gelza Teixeira, mestra em Ci\u00eancia do Solo, explica que o sil\u00edcio mant\u00e9m o potencial h\u00eddrico foliar, realizando o ajuste osm\u00f3tico das c\u00e9lulas. Al\u00e9m disso, ele auxilia nas trocas gasosas do processo de respira\u00e7\u00e3o das plantas.<\/p>\n<p>Essa modula\u00e7\u00e3o do metabolismo das plantas e altera\u00e7\u00e3o das atividades fisiol\u00f3gicas favorece a cultura em condi\u00e7\u00f5es de <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/qual-a-importancia-do-silicio-na-minimizacao-do-estresse-hidrico-em-plantas\/\">estresse h\u00eddrico<\/a>, seja ele causado pela seca ou pela presen\u00e7a de outros fatores, como em <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/salinidade-do-solo-uma-ameaca-a-produtividade-agricola\/\">solos com elevado \u00edndice salino<\/a>.<\/p>\n<p>Como, ent\u00e3o, obter bons resultados com os benef\u00edcios da aplica\u00e7\u00e3o de sil\u00edcio na cana?<\/p>\n<div class=\"verde-content_3\" id=\"verde-304317181\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2><strong>A import\u00e2ncia da aplica\u00e7\u00e3o do sil\u00edcio na cana<\/strong><\/h2>\n<p>Em resumo, o sil\u00edcio traz diversos benef\u00edcios para a cultura da cana. Entretanto, em solos tropicais, que podem ser mais arenosos e t\u00eam baixa concentra\u00e7\u00e3o de sil\u00edcio, existe a necessidade de fazer a aduba\u00e7\u00e3o silicatada.<\/p>\n<p>Estudos como o artigo <em>Symptoms of plant malnutrition silicon an ergonomically essential nutrient for sugarcane, <\/em>de Robert L. Fox e James A. Silva, inclusive mostram que a resposta da aduba\u00e7\u00e3o com sil\u00edcio na cana tem respostas melhores nesse tipo de solo. Isso porque \u00a0os teores desse elemento neles podem chegar a estar abaixo de 2 mg\/kg no extrato saturado.<\/p>\n<p>Assim, incluir o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/conheca-as-principais-fontes-de-silicio-para-agricultura\/\">uso de fontes de sil\u00edcio<\/a> no programa de aduba\u00e7\u00e3o da cana \u00e9 essencial para desfrutar todos os benef\u00edcios que esse elemento pode proporcionar aos canaviais!<\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/produza\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=MOND\u00c9-BANNER-MOBILE\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/MONDE_Banner_Mobile.jpg\" alt=\"-\" width=\"800\" height=\"400\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/produza\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=MOND\u00c9-BANNER-DESKTOP\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/MONDE_Banner_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O sil\u00edcio \u00e9 considerado o elemento mais absorvido e acumulado pelos canaviais. Descubra quais os benef\u00edcios do sil\u00edcio na cana!<\/p>\n","protected":false},"author":7,"featured_media":5551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[17,197],"tags":[499,504,885,503],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/5543"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=5543"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/5543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/5551"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=5543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=5543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=5543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}