{"id":3039,"date":"2021-05-06T22:08:55","date_gmt":"2021-05-07T01:08:55","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=3039"},"modified":"2023-01-16T15:12:24","modified_gmt":"2023-01-16T18:12:24","slug":"descubra-as-vantagens-do-uso-da-ulexita-como-fonte-de-boro-na-agricultura","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/solo\/descubra-as-vantagens-do-uso-da-ulexita-como-fonte-de-boro-na-agricultura\/","title":{"rendered":"Descubra as vantagens do uso da ulexita como fonte de boro na agricultura"},"content":{"rendered":"<p>Embora normalmente seja requerido em pequenas quantidades pelas plantas, o boro \u00e9 um elemento que tem fun\u00e7\u00f5es muito importantes no desenvolvimento vegetal. Assim, manter os n\u00edveis adequados de boro no solo \u00e9 essencial para que o agricultor tenha mais produtividade e qualidade na lavoura. A escolha de fontes adequadas de boro \u00e9 um passo importante para atingir esse objetivo. Descubra quais s\u00e3o as vantagens do uso da ulexita como fonte de boro na agricultura.<\/p>\n<h2>Por que \u00e9 preciso realizar a aduba\u00e7\u00e3o com boro?<\/h2>\n<p>O boro \u00e9 um elemento que pertence ao grupo dos micronutrientes. Isso significa que ele \u00e9 requerido em menor quantidade pelas plantas. Entretanto, isso n\u00e3o significa que ele n\u00e3o \u00e9 importante no desenvolvimento vegetal. Ele participa de muitos processos bioqu\u00edmicos essenciais, entre eles:<\/p>\n<ul>\n<li>Forma\u00e7\u00e3o de novos tecidos;<\/li>\n<li>S\u00edntese da parede celular;<\/li>\n<li>Lignifica\u00e7\u00e3o;<\/li>\n<li>Garantia da integridade da membrana celular;<\/li>\n<li>Metabolismo de carboidratos e de horm\u00f4nios vegetais;<\/li>\n<li>Ativa\u00e7\u00e3o enzim\u00e1tica;<\/li>\n<li>S\u00edntese proteica.<\/li>\n<\/ul>\n<p>O renomado engenheiro agr\u00f4nomo Eur\u00edpedes Malavolta, no estudo <em>Micronutrientes e metais pesados, mitos, mistifica\u00e7\u00e3o e fatos<\/em>, aponta que muitas culturas no Brasil s\u00e3o deficientes em boro. Algumas, como o caf\u00e9, tem uma defici\u00eancia bastante elevada do nutriente.<\/p>\n<p>Assim, incluir o boro no manejo nutricional agr\u00edcola \u00e9 muito importante para garantir que as lavouras alcancem bons n\u00edveis de produtividade e de qualidade dos alimentos produzidos. Entretanto, a aduba\u00e7\u00e3o com boro tem alguns desafios que precisam ser levados em conta na hora de pensar nesse manejo nutricional.<\/p>\n<div class=\"verde-content_3\" id=\"verde-3855047735\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2>O desafio do equil\u00edbrio na aduba\u00e7\u00e3o com boro<\/h2>\n<p>Como ele \u00e9 exigido em pequenas quantidades\u00a0 um dos grandes desafios na hora de pensar na aduba\u00e7\u00e3o com boro \u00e9 encontrar a faixa de equil\u00edbrio entre fornecer pouca quantidade ou fornecer uma quantidade excessiva desse nutriente.<\/p>\n<p>A defici\u00eancia de boro pode provocar sintomas que incluem clorose, necrose e deforma\u00e7\u00f5es nas folhas jovens e nos perfilhos, diminuindo a produtividade e qualidade da lavoura. Por outro lado, o excesso de boro no solo pode provocar sintomas de toxidez.<\/p>\n<p>Fontes de boro mais convencionais, como o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/o-que-e-o-fertilizante-acido-borico\/\">\u00e1cido b\u00f3rico<\/a>, s\u00e3o muito sol\u00faveis. Isso significa que elas conseguem disponibilizar o boro para as plantas muito rapidamente. Entretanto, a pesquisadora Isabela Rodrigues Bologna, em sua \u00a0disserta\u00e7\u00e3o de mestrado <em>Aduba\u00e7\u00e3o boratada em pomar de laranja p\u00eara rio afetado pela clorose variegada dos citros, <\/em>destaca que:<\/p>\n<p>\u201cA alta disponibilidade inicial pode provocar sintomas de toxidez em culturas suscept\u00edveis em est\u00e1gios iniciais de desenvolvimento.\u201d<\/p>\n<p>Outra limita\u00e7\u00e3o das fontes de boro muito sol\u00faveis \u00e9 que elas trazem o problema da lixivia\u00e7\u00e3o. Esse fen\u00f4meno acontece quando os nutrientes se perdem para as camadas mais profundas do solo, ficando fora do alcance das ra\u00edzes, em decorr\u00eancia do excesso de chuvas ou da irriga\u00e7\u00e3o mal planejada.<\/p>\n<p>John Jacob Mortvedt, pesquisador e autoridade em fertilizantes de micronutrientes, no artigo <em>Needs for controlled availability micronutrient fertilizers, <\/em>ressalta que a maioria das fontes de boro sofre com o problema da lixivia\u00e7\u00e3o.<\/p>\n<p>J\u00e1 no artigo <em>Lixivia\u00e7\u00e3o e disponibilidade de boro em fun\u00e7\u00e3o de fontes e caracter\u00edsticas de solos, <\/em>a pesquisadora do Instituto Agron\u00f4mico de Campinas, Cleide Aparecida de Abreu, escreve que, quando ocorre a lixivia\u00e7\u00e3o, ainda que seja realizada a aplica\u00e7\u00e3o de fertilizantes, o solo acaba ficando deficiente em boro. A pesquisadora nota que isso afeta particularmente os solos arenosos, que ocorrem em diversas regi\u00f5es do Brasil.<\/p>\n<p>Entretanto, existem fontes de boro que apresentam uma disponibiliza\u00e7\u00e3o mais gradual. \u00c9 o caso da <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-o-que-e-a-ulexita-e-porque-ela-e-uma-fonte-de-boro-vantajosa\/\">ulexita<\/a>, que depois de processada, tem potencial para ser utilizada como fonte de boro. Mas, quais s\u00e3o as vantagens do uso da ulexita na agricultura?<\/p>\n<h2>A ulexita \u00e9 uma fonte de boro com menos lixivia\u00e7\u00e3o<\/h2>\n<p>A ulexita \u00e9 um mineral cuja f\u00f3rmula qu\u00edmica \u00e9 NaCaB<sub>5<\/sub>O<sub>6<\/sub>(OH)<sub>6<\/sub>.5(H<sub>2<\/sub>O). Encontrada em regi\u00f5es \u00e1ridas, praias salinas e lagos salinos ressecados, ela pertence \u00e0 classe dos boratos, sendo mais especificamente um borato hidratado de s\u00f3dio e c\u00e1lcio. Como sugerido pelo nome da sua classe mineral\u00f3gica, o boro \u00e9 um dos elementos presentes na composi\u00e7\u00e3o da ulexita.<\/p>\n<p>A ulexita tem um teor baixo de solubilidade em \u00e1gua. Enquanto a solubilidade do <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/o-que-e-o-fertilizante-acido-borico\/\">\u00e1cido b\u00f3rico<\/a>, por exemplo, fica em torno de 49 g\/L (gramas por litro) a 20\u00ba C, a da ulexita \u00e9 de apenas 0,9 g\/L a 20\u00ba.<\/p>\n<p>Com uma solubilidade menor, a ulexita est\u00e1 menos sujeita \u00e0 lixivia\u00e7\u00e3o quando utilizada como fonte de boro na agricultura.<\/p>\n<div style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3040\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Neossolo-Quartzarenico-Ortico-Tipico-em-funcao-de-diferentes-fontes-aplicadas.png\" alt=\"Compara\u00e7\u00e3o de boro acumulado nos lixiviados no Neossolo Quartzar\u00eanico \u00d3rtico T\u00edpico, em fun\u00e7\u00e3o de diferentes fontes aplicadas (Fonte: ABREU, Cleide et. al, 2015)\" width=\"521\" height=\"441\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Neossolo-Quartzarenico-Ortico-Tipico-em-funcao-de-diferentes-fontes-aplicadas.png 521w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Neossolo-Quartzarenico-Ortico-Tipico-em-funcao-de-diferentes-fontes-aplicadas-300x254.png 300w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Neossolo-Quartzarenico-Ortico-Tipico-em-funcao-de-diferentes-fontes-aplicadas-251x212.png 251w\" sizes=\"(max-width: 521px) 100vw, 521px\" title=\"\"><\/div>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Compara\u00e7\u00e3o de boro acumulado nos lixiviados no Neossolo Quartzar\u00eanico \u00d3rtico T\u00edpico, em fun\u00e7\u00e3o de diferentes fontes aplicadas (Fonte: ABREU, Cleide et. al, 2015)<\/em><\/p>\n<div style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3043\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Latossolo-.png\" alt=\"Compara\u00e7\u00e3o de boro acumulado nos lixiviados no Latossolo Vermelho Eutrof\u00e9rrico T\u00edpico em fun\u00e7\u00e3o de diferentes fontes aplicadas (Fonte: ABREU, Cleide, 2015)\" width=\"480\" height=\"418\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Latossolo-.png 480w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Latossolo--300x261.png 300w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Comparacao-de-boro-acumulado-nos-lixiviados-no-Latossolo--251x219.png 251w\" sizes=\"(max-width: 480px) 100vw, 480px\" title=\"\"><\/div>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Compara\u00e7\u00e3o de boro acumulado nos lixiviados no Gleissolo Mel\u00e2nico Distr\u00f3fico T\u00edpico em fun\u00e7\u00e3o de diferentes fontes aplicadas (Fonte: ABREU, Cleide 2015)<\/em><\/p>\n<div style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3044\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Isso-traz-a-vantagem-para-o-agricultor-de-nao-perder-parte-do-boro.png\" alt=\"Compara\u00e7\u00e3o de boro acumulado nos lixiviados no Gleissolo Mel\u00e2nico Distr\u00f3fico T\u00edpico em fun\u00e7\u00e3o de diferentes fontes aplicadas (Fonte: ABREU, Cleide 2015)\" width=\"480\" height=\"397\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Isso-traz-a-vantagem-para-o-agricultor-de-nao-perder-parte-do-boro.png 480w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Isso-traz-a-vantagem-para-o-agricultor-de-nao-perder-parte-do-boro-300x248.png 300w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Isso-traz-a-vantagem-para-o-agricultor-de-nao-perder-parte-do-boro-251x208.png 251w\" sizes=\"(max-width: 480px) 100vw, 480px\" title=\"\"><\/div>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Compara\u00e7\u00e3o de boro acumulado nos lixiviados no Gleissolo Mel\u00e2nico Distr\u00f3fico T\u00edpico em fun\u00e7\u00e3o de diferentes fontes aplicadas (Fonte: ABREU, Cleide 2015)<\/em><\/p>\n<p>Isso traz a vantagem para o agricultor de n\u00e3o perder parte do boro para os perfis mais profundos do solo, al\u00e9m de n\u00e3o correr o risco de ficar com o solo deficiente nesse nutriente mesmo realizando a aduba\u00e7\u00e3o.<\/p>\n<h2>O uso da ulexita diminui o risco de toxidez por superdosagem do boro<\/h2>\n<p>Outra vantagem do uso da ulexita como fonte de boro na agricultura \u00e9 que ela tem uma libera\u00e7\u00e3o gradual dos seus nutrientes. A raz\u00e3o disso \u00e9 que o boro contido na ulexita passa por uma rea\u00e7\u00e3o, que normalmente acontece com a acidez natural do solo, para se transformar na forma que as plantas conseguem absorver.<\/p>\n<p>Aliada \u00e0 sua menor solubilidade, a libera\u00e7\u00e3o gradual dos nutrientes da ulexita a tornam uma fonte de boro mais vantajosa na manuten\u00e7\u00e3o dos n\u00edveis de boro do solo. Isso porque, assim. h\u00e1 a diminui\u00e7\u00e3o dos riscos de que o boro seja disponibilizado de uma \u00fanica vez, causando defici\u00eancia \u00e0 longo prazo e o risco de toxidez com a superdosagem inicial.<\/p>\n<p>Essas caracter\u00edsticas trazem ainda mais uma vantagem, que \u00e9 a otimiza\u00e7\u00e3o da rela\u00e7\u00e3o custo-benef\u00edcio do fertilizante para o agricultor. Isso acontece porque, disponibilizando os nutrientes gradualmente e com menor lixivia\u00e7\u00e3o, os n\u00edveis de boro no solo ficam estabilizados pro mais tempo.<\/p>\n<p>A longo prazo, isso acaba gerando economia para o agricultor, uma vez que h\u00e1 um efeito residual do boro nos sistemas de rota\u00e7\u00e3o de culturas, trazendo mais aproveitamento da aduba\u00e7\u00e3o no ciclo produtivo, e a diminui\u00e7\u00e3o do n\u00famero de reaplica\u00e7\u00f5es no caso das culturas perenes.<\/p>\n<h2>Torne o manejo nutricional mais eficiente com a ulexita<\/h2>\n<p>A necessidade da inclus\u00e3o do boro no manejo nutricional agr\u00edcola \u00e9 essencial para melhorar os n\u00edveis de produtividade e qualidade das lavouras. Entretanto, a aduba\u00e7\u00e3o com esse nutriente tem particularidades e desafios que exigem a <a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/ulexita-ou-acido-borico-qual-fonte-de-boro-escolher-para-a-lavoura\/\">busca de fontes adequadas<\/a>.<\/p>\n<p>A ulexita, com seu baixo teor de lixivia\u00e7\u00e3o e libera\u00e7\u00e3o gradual de nutrientes, oferece vantagens para o agricultor na hora de realizar a aduba\u00e7\u00e3o com boro. Desse modo, f<a href=\"https:\/\/blog.verde.ag\/pt\/produtos-da-verde\/entenda-o-que-e-o-baks-e-as-suas-vantagens-para-uma-nova-agricultura\/\">ertilizantes que utilizam a ulexita como mat\u00e9ria prima<\/a> t\u00eam uma rela\u00e7\u00e3o custo-benef\u00edcio melhor e tornam o manejo nutricional mais eficiente.<\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-MOBILE\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Mobile.jpg\" alt=\"-\" width=\"800\" height=\"400\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-DESKTOP\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>Bons n\u00edveis de boro no solo s\u00e3o essenciais para a produtividade e qualidade na lavoura. Quais s\u00e3o as vantagens do uso da ulexita como fonte de boro?<\/p>\n","protected":false},"author":7,"featured_media":3045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,197],"tags":[155,886,215,924,183],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/3039"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=3039"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/3039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/3045"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=3039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=3039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=3039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}