{"id":3020,"date":"2021-05-04T21:17:09","date_gmt":"2021-05-05T00:17:09","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=3020"},"modified":"2023-01-10T14:34:57","modified_gmt":"2023-01-10T17:34:57","slug":"entenda-porque-e-importante-otimizar-a-adubacao-com-potassio","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-porque-e-importante-otimizar-a-adubacao-com-potassio\/","title":{"rendered":"Entenda porque \u00e9 importante otimizar a aduba\u00e7\u00e3o com pot\u00e1ssio"},"content":{"rendered":"<p>O pot\u00e1ssio (K) pertence ao grupo dos macronutrientes prim\u00e1rios, sendo, de maneira geral, absorvido em grandes quantidades. Entenda a import\u00e2ncia que esse elemento tem para as plantas e a necessidade de nutrir adequadamente o solo com pot\u00e1ssio.<\/p>\n<h2>A import\u00e2ncia do pot\u00e1ssio para as plantas<\/h2>\n<p>Os macronutrientes prim\u00e1rios s\u00e3o um grupo de elementos absorvidos em grandes quantidades pelas plantas, estando inclusos o nitrog\u00eanio (N), f\u00f3sforo (P) e pot\u00e1ssio (K). Dentre os tr\u00eas, o pot\u00e1ssio normalmente \u00e9 o segundo elemento mais requerido pelas plantas, estando envolvido em fun\u00e7\u00f5es essenciais, tais como:<\/p>\n<ul>\n<li>Melhoria da qualidade do produto agr\u00edcola;<\/li>\n<li>Ativa\u00e7\u00e3o enzim\u00e1tica;<\/li>\n<li>S\u00edntese proteica;<\/li>\n<li>Fotoss\u00edntese;<\/li>\n<li>Transporte de fotossintatos no floema;<\/li>\n<li>Crescimento celular;<\/li>\n<li>Regula\u00e7\u00e3o do potencial h\u00eddrico das c\u00e9lulas;<\/li>\n<li>Ameniza\u00e7\u00e3o de estresses bi\u00f3ticos e abi\u00f3ticos.<\/li>\n<\/ul>\n<p>Uma vez no solo, o pot\u00e1ssio \u00e9 preferencialmente absorvido pelo sistema radicular da planta na forma do \u00edon K<sup>+<\/sup>. De maneira geral, os solos brasileiros apresentam baixo teor de pot\u00e1ssio, variando entre 0,05 a 2,5%.<\/p>\n<p>O estudo <em>Aspectos relacionados ao mapeamento da disponibilidade de pot\u00e1ssio nos solos do Brasil<\/em>, feito pela Empresa Brasileira de Pesquisa Agropecu\u00e1ria (Embrapa), mostra que, em rela\u00e7\u00e3o a disponibilidade, 43,3% dos solos brasileiros t\u00eam disponibilidade baixa ou muito baixa de pot\u00e1ssio, ao passo que somente 4,4% t\u00eam disponibilidade muito alta.<\/p>\n<p>Para entender se a quantidade dispon\u00edvel de pot\u00e1ssio no solo est\u00e1 suprindo a demanda nutricional da planta, devem ser realizadas an\u00e1lises de solo e <a href=\"https:\/\/blog.verde.ag\/pt\/potassio\/analise-foliar-de-potassio-importante-tecnica-para-produtividade-da-lavoura\/\">an\u00e1lises foliares da cultura<\/a>. Outra ferramenta dispon\u00edvel para o agricultor \u00e9 a diagnose visual.<\/p>\n<div>Segundo o engenheiro agr\u00f4nomo e Dr. em fitotecnia Jos\u00e9 Lu\u00eds da Silva Nunes, um dos sintomas mais comuns da defici\u00eancia de pot\u00e1ssio nas plantas \u00e9 o amarelecimento ao longo das margens da folha, que leva a dificuldades na realiza\u00e7\u00e3o de fotoss\u00edntese e queda das folhas em casos mais graves.<\/div>\n<div><\/div>\n<div style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3022\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Deficiencia-de-potassio-K-na-cultura-da-soja-evidenciada-pela-borda-amarelada-ao-longo-das-margens-da-folha.png\" alt=\"Defici\u00eancia de pot\u00e1ssio (K) na cultura da soja, evidenciada pela borda amarelada ao longo das margens da folha. (Fonte: Embrapa Soja)\" width=\"480\" height=\"320\" srcset=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Deficiencia-de-potassio-K-na-cultura-da-soja-evidenciada-pela-borda-amarelada-ao-longo-das-margens-da-folha.png 480w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Deficiencia-de-potassio-K-na-cultura-da-soja-evidenciada-pela-borda-amarelada-ao-longo-das-margens-da-folha-300x200.png 300w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Deficiencia-de-potassio-K-na-cultura-da-soja-evidenciada-pela-borda-amarelada-ao-longo-das-margens-da-folha-360x240.png 360w, https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/05\/Deficiencia-de-potassio-K-na-cultura-da-soja-evidenciada-pela-borda-amarelada-ao-longo-das-margens-da-folha-251x167.png 251w\" sizes=\"(max-width: 480px) 100vw, 480px\" title=\"\"><\/div>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Defici\u00eancia de pot\u00e1ssio (K) na cultura da soja, evidenciada pela borda amarelada ao longo das margens da folha. (Fonte: Embrapa Soja)<\/em><\/p>\n<div>Entretanto, quando os sintomas est\u00e3o vis\u00edveis na planta, a defici\u00eancia nutricional j\u00e1 atingiu n\u00edveis que comprometeram a produtividade da cultura. Al\u00e9m disso, baixos n\u00edveis de pot\u00e1ssio tamb\u00e9m fazem com que as plantas apresentem uma menor resist\u00eancia \u00e0s estiagens, excesso de \u00e1gua, baixas temperaturas, pragas e doen\u00e7as.<\/div>\n<p>Considerando as caracter\u00edsticas do solo brasileiro e a import\u00e2ncia do pot\u00e1ssio para as plantas, \u00e9 necess\u00e1rio recorrer a alternativas para que o agricultor possa suprir a demanda nutricional da sua lavoura.<\/p>\n<div class=\"verde-content_3\" id=\"verde-2487209210\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2>As fontes de pot\u00e1ssio para a agricultura<\/h2>\n<p>As fontes de pot\u00e1ssio para a agricultura s\u00e3o diversas, perpassando desde fontes org\u00e2nicas a qu\u00edmicas. Dentre elas, as mais empregadas na agricultura s\u00e3o os fertilizantes, que tamb\u00e9m apresentam uma grande variedade de produtos dispon\u00edveis no mercado, considerando as diferentes vantagens e desvantagens que cada produto apresenta.<\/p>\n<p>Um dos tipos de fertilizantes qu\u00edmicos mais convencionais utilizados s\u00e3o as \u201cformula\u00e7\u00f5es NPK\u201d. \u00a0Elas possuem uma ampla variedade de formula\u00e7\u00f5es dispon\u00edveis prontamente no mercado, atendendo diversas culturas, sendo atualmente uma das fontes mais usadas pelo mercado agr\u00edcola.<\/p>\n<p>Al\u00e9m das formula\u00e7\u00f5es NPK, alguns outros fertilizantes espec\u00edficos utilizados como fonte de pot\u00e1ssio s\u00e3o os <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-as-vantagens-e-desvantagens-do-sulfato-de-potassio\/\">sulfatos<\/a>, <a href=\"https:\/\/blog.verde.ag\/pt\/potassio\/entenda-o-que-e-o-nitrato-de-potassio-e-se-ele-e-um-fertilizante-vantajoso\/\">nitratos<\/a> e cloretos de pot\u00e1ssio, al\u00e9m dos fertilizantes minerais feitos a partir de rochas como a <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/conheca-a-biotita-e-seu-uso-como-fonte-de-potassio-agricola\/\">biotita<\/a> e <span class=\"TextRun BCX0 SCXW122643768\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun BCX0 SCXW122643768\">o\u00a0<\/span><\/span><a class=\"Hyperlink BCX0 SCXW122643768\" href=\"https:\/\/blog.verde.ag\/pt\/potassio\/o-que-e-o-siltito-glauconitico-e-como-ele-pode-ser-utilizado-como-fertilizante-agricola\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined BCX0 SCXW122643768\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun CommentStart BCX0 SCXW122643768\" data-ccp-charstyle=\"Hyperlink\">Siltito\u00a0<\/span><\/span><span class=\"TextRun Underlined BCX0 SCXW122643768\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun BCX0 SCXW122643768\" data-ccp-charstyle=\"Hyperlink\">Glaucon\u00edtico<\/span><\/span><\/a><span class=\"TextRun BCX0 SCXW122643768\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun BCX0 SCXW122643768\">.<\/span><\/span><\/p>\n<p>O fertilizante que mais se destaca em rela\u00e7\u00e3o a quantidade empregada na agricultura \u00e9 o <a href=\"https:\/\/blog.verde.ag\/pt\/potassio\/saiba-o-que-e-o-cloreto-de-potassio-e-veja-se-vale-a-pena-usar-esse-fertilizante\/\">Cloreto de Pot\u00e1ssio (KCl)<\/a>. Apesar de ser uma das fontes mais concentradas do nutriente, ele ainda apresenta uma s\u00e9rie de limita\u00e7\u00f5es e desvantagens no campo.<\/p>\n<h2>As limita\u00e7\u00f5es do Cloreto de Pot\u00e1ssio<\/h2>\n<p>O KCl cont\u00e9m aproximadamente 53% de pot\u00e1ssio e 47% de cloro. Apesar de apresentar um alto teor de pot\u00e1ssio, \u00a0o Cloreto de Pot\u00e1ssio apresenta uma s\u00e9rie de desvantagens, como:<\/p>\n<ul>\n<li>Forma\u00e7\u00e3o de cloro gasoso;<\/li>\n<li>Ser altamente suscet\u00edvel \u00e0 lixivia\u00e7\u00e3o, devido a sua alta solubilidade;<\/li>\n<li>Apresentar um dos maiores \u00edndices de salinidade, dentre as fontes de pot\u00e1ssio;<\/li>\n<\/ul>\n<p>No solo, o Cloreto de Pot\u00e1ssio se combina com nitratos formando o cloro gasoso. A consequ\u00eancia \u00e9 a diminui\u00e7\u00e3o do ar no solo, que reduz a respira\u00e7\u00e3o da raiz e aumenta a produ\u00e7\u00e3o de componentes t\u00f3xicos pelas plantas, resultando na redu\u00e7\u00e3o dos microrganismos presentes no solo e quebra da mat\u00e9ria org\u00e2nica.<\/p>\n<p>Al\u00e9m disso, como \u00e9 um fertilizante que apresenta uma elevada solubilidade, o KCl tem uma grande mobilidade no perfil do solo. Isso faz com que ele apresente uma tend\u00eancia em se deslocar mais facilmente para as camadas mais profundas do solo. Devido \u00e0 aus\u00eancia do efeito residual, exige um maior n\u00famero de aplica\u00e7\u00f5es do insumo ao longo dos ciclos produtivos das culturas.<\/p>\n<p>Uma consequ\u00eancia do maior n\u00famero de aplica\u00e7\u00f5es do Cloreto de Pot\u00e1ssio \u00e9 o aumento da salinidade do solo, j\u00e1 que ele apresenta um elevado \u00edndice salino de 116%. O <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/salinidade-do-solo-uma-ameaca-a-produtividade-agricola\/\">ac\u00famulo de sais no solo <\/a>gera a eleva\u00e7\u00e3o do estresse h\u00eddrico nas plantas, o que pode levar, por exemplo,a diminui\u00e7\u00e3o no rendimento de gr\u00e3os.<\/p>\n<p>A aplica\u00e7\u00e3o de altas doses de cloreto tamb\u00e9m pode gerar um desbalanceamento do equil\u00edbrio fosfato:pot\u00e1ssio no solo e as plantas podem apresentar acumula\u00e7\u00e3o excessiva de cloro nas folhas.<\/p>\n<p>Isso pode ser prejudicial \u00e0s plantas. O professor Thimothy Ellsworth, no estudo <em>The Potassium paradox: Implications for soil fertility, crop production and human health,<\/em> \u00a0ressalta que \u201cmuitas culturas leguminosas, incluindo a soja, s\u00e3o sens\u00edveis a toxicidade do cloro\u201d.<\/p>\n<p>A Doutora e especialista em Solos e Nutri\u00e7\u00e3o de Plantas, Michele Megda, explica mais sobre as consequ\u00eancias da utiliza\u00e7\u00e3o do Cloreto de Pot\u00e1ssio:<\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_70247\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/3_xP77RPtHs?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<h2>A escolha da fonte de pot\u00e1ssio sempre deve ser consciente<\/h2>\n<p>A escolha da fonte de pot\u00e1ssio para sua lavoura sempre deve ser feita de forma consciente, sendo necess\u00e1rio cada vez mais compreender as diferentes rela\u00e7\u00f5es que se estabelecem entre o insumo e o seu agroecossistema.<\/p>\n<p>Ao se entender as diferentes vantagens e desvantagens de cada fonte de pot\u00e1ssio e as taxas mais adequadas para o fornecimento do insumo, o agricultor consegue garantir uma boa qualidade e produtividade da sua lavoura.<\/p>\n<p>Nesse processo, o aux\u00edlio de profissionais qualificados se torna imprescind\u00edvel, para garantir que todas as fases, desde a interpreta\u00e7\u00e3o da an\u00e1lise foliar e do solo, \u00e0 aplica\u00e7\u00e3o do insumo, sejam feitas de forma correta.<\/p>\n<p>Al\u00e9m disso, o agricultor pode cada vez mais contar com novas fontes sustent\u00e1veis de pot\u00e1ssio que s\u00e3o livres de cloro, como o <a href=\"https:\/\/blog.verde.ag\/pt\/solo\/conheca-todos-os-beneficios-do-uso-do-siltito-glauconitico-como-fertilizante-na-agricultura\/\">Siltito Glaucon\u00edtico<\/a>. Ele traz ainda as vantagens da <a href=\"https:\/\/blog.verde.ag\/pt\/potassio\/entenda-o-que-e-a-glauconita-e-os-beneficios-do-seu-uso-como-fertilizante\/\">glauconita<\/a>, que melhora as propriedades f\u00edsicas e qu\u00edmicas do solo. Al\u00e9m disso, a sua libera\u00e7\u00e3o gradual dos nutrientes proporciona um efeito residual que mant\u00e9m os n\u00edveis de pot\u00e1ssio no solo por mais tempo.<\/p>\n<p>Estar atento \u00e0s pesquisas e novas tecnologias da \u00e1rea, bem como analisar sempre as melhores op\u00e7\u00f5es que est\u00e3o \u00e0 disposi\u00e7\u00e3o do agricultor, que v\u00e3o tornar o uso do solo mais sustent\u00e1vel, s\u00e3o a chave para otimizar a aduba\u00e7\u00e3o com pot\u00e1ssio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe qual a import\u00e2ncia que o pot\u00e1ssio tem para as plantas e quanto \u00e9 necess\u00e1rio nutrir adequadamente o solo e otimizar a aduba\u00e7\u00e3o?<\/p>\n","protected":false},"author":7,"featured_media":3022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[197],"tags":[34,885,77,158],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/3020"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=3020"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/3020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/3022"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=3020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=3020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=3020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}