{"id":2619,"date":"2021-03-22T20:45:38","date_gmt":"2021-03-22T23:45:38","guid":{"rendered":"https:\/\/blog.verde.ag\/pt\/?p=2619"},"modified":"2024-03-13T12:02:55","modified_gmt":"2024-03-13T15:02:55","slug":"enxofre-elementar-pastilhado","status":"publish","type":"post","link":"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/enxofre-elementar-pastilhado\/","title":{"rendered":"O que \u00e9 e qual a efici\u00eancia do enxofre elementar pastilhado como fertilizante?"},"content":{"rendered":"<p>Voc\u00ea sabe o que \u00e9 o enxofre elementar pastilhado? Essa \u00e9 uma das formas de fornecer enxofre para as plantas. Com a baixa disponibilidade nos solos brasileiros e sendo o quarto nutriente mais consumido durante o desenvolvimento das plantas, o enxofre ganha um papel muito relevante dentro do manejo de nutri\u00e7\u00e3o agr\u00edcola. Mas o enxofre elementar pastilhado \u00e9 a maneira mais eficiente de incluir esse elemento no manejo nutricional?<\/p>\n<h2>O enxofre e sua import\u00e2ncia para as plantas<\/h2>\n<p>O enxofre faz parte do grupo de nutrientes chamado de macronutrientes secund\u00e1rios, juntamente com o c\u00e1lcio e o magn\u00e9sio. Ele tem <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/saiba-quais-sao-as-vantagens-do-enxofre-elementar-micronizado-para-a-sua-lavoura\/\">um papel essencial no metabolismo das plantas<\/a>, como evidenciado pela P\u00f3s Doutoranda em Agronomia pela Universidade Estadual do Mato Grosso do Sul, Dra. Ilca Puertas:<\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_89858\"  width=\"1170\" height=\"658\"  data-origwidth=\"1170\" data-origheight=\"658\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/quHMYyPcfr0?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=1&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p style=\"padding-top: 10px;\">O principal sintoma de defici\u00eancia de enxofre em uma lavoura \u00e9 um amarelamento generalizado das folhas, provocado pela redu\u00e7\u00e3o dr\u00e1stica no conte\u00fado de clorofila. Isso acontece porque \u00e9 essa a subst\u00e2ncia respons\u00e1vel pela pigmenta\u00e7\u00e3o verde das folhas e est\u00e1 diretamente envolvida na fotoss\u00edntese, ou seja, na gera\u00e7\u00e3o de energia para as plantas.<\/p>\n<p>Al\u00e9m disso, o enxofre est\u00e1 envolvido em processos metab\u00f3licos como:<\/p>\n<ul>\n<li>Processos de respira\u00e7\u00e3o;<\/li>\n<li>Processos de crescimento;<\/li>\n<li>S\u00edntese de vitaminas e prote\u00ednas;<\/li>\n<li>Mecanismos de resposta a estresses oxidativos e resist\u00eancia ao frio.<\/li>\n<\/ul>\n<p>Apesar dessa relev\u00e2ncia para planta, a maioria dos solos brasileiros n\u00e3o apresentam quantidades relevantes de enxofre por serem antigos e muito intemperizados. Por isso, para evitar que haja uma defici\u00eancia do elemento nas plantas, \u00e9 preciso que se fa\u00e7a a aduba\u00e7\u00e3o com enxofre durante o manejo agr\u00edcola.<\/p>\n<div class=\"verde-content_3\" id=\"verde-806029209\"><a class=\"text-color-btn\" href=\"https:\/\/wa.me\/5531999206297?text=Ol%C3%A1%2C%20vi%20o%20artigo%20no%20blog%20e%20gostaria%20de%20saber%20mais%20sobre%20os%20fertilizantes%20da%20Verde%20Agritech\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n    <button class=\"btn-form-blog\">Quero revolucionar a produ\u00e7\u00e3o da minha lavoura<\/button>\r\n<\/a>\r\n\r\n<style>\r\n    .text-color-btn {\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n        text-decoration: none; \/* Adicionado para evitar sublinhado no link *\/\r\n        display: inline-block;\r\n    }\r\n\r\n    .btn-form-blog {\r\n        padding: 14px;\r\n        background-color: #38a38c;\r\n        color: #fff;\r\n        border: none;\r\n        border-radius: 20px;\r\n        cursor: pointer;\r\n    }\r\n\r\n    .text-color-btn:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    .btn-form-blog:hover {\r\n        background-color: #333;\r\n        transition: 0.4s;\r\n    }\r\n\r\n    @media only screen and (max-width: 600px) {\r\n        .text-color-btn {\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n        .btn-form-blog {\r\n            padding: 14px;\r\n            background-color: #38a38c;\r\n            color: #fff;\r\n        }\r\n    }\r\n<\/style><\/div><h2>O que \u00e9 o enxofre elementar e suas diferentes formas<\/h2>\n<p>O enxofre pode estar presente nos insumos agr\u00edcolas como sulfato (SO<sub>4<\/sub><sup>2-<\/sup>), elementar ou ainda como uma combina\u00e7\u00e3o de ambos. O enxofre sulfatado \u00e9 a forma que as plantas conseguem absorver esse nutriente, estando presente em muitos dos fertilizantes mais convencionais, como o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-as-vantagens-e-desvantagens-do-uso-do-super-simples-como-adubo\/\">super simples<\/a>, o <a href=\"https:\/\/blog.verde.ag\/pt\/nutricao-de-plantas\/entenda-o-que-e-o-sulfato-de-amonio-e-o-seu-uso-como-adubo\/\">sulfato de am\u00f4nio<\/a> e o gesso.<\/p>\n<p>Entretanto, o enxofre sulfatado \u00e9 altamente lixivi\u00e1vel, o que faz com que ele se mova pelo perfil do solo com mais facilidade e se perca para as camadas mais profundas. Processo esse que pode ser intensificado a depender da textura do solo.<\/p>\n<p>J\u00e1 o enxofre elementar \u00e9 uma fonte composta por 99% de enxofre, podendo ser obtido de fontes naturais do elemento, como as rochas elementares, jazidas origem vulc\u00e2nica e em dep\u00f3sitos do min\u00e9rio sulfureto de hidrog\u00eanio durante o processamento de combust\u00edvel f\u00f3ssil.<\/p>\n<p>O enxofre elementar tem a vantagem de ter uma libera\u00e7\u00e3o gradual, o que faz com que o elemento esteja presente no solo por mais tempo e esteja menos sujeito a lixivia\u00e7\u00e3o. Al\u00e9m disso, ele n\u00e3o tem um n\u00edvel salino elevado, o que elimina a necessidade de parcelamento na hora da aplica\u00e7\u00e3o.<\/p>\n<p>Para que haja a disponibiliza\u00e7\u00e3o do enxofre elementar para o solo e, em consequ\u00eancia para as plantas, ele precisa passar por um processo de oxida\u00e7\u00e3o, que envolve os microrganismos presentes no solo.<\/p>\n<p>Em seu uso na agricultura, o enxofre elementar pode ser:<\/p>\n<ul>\n<li>Granulado;<\/li>\n<li>Pastilhado;<\/li>\n<li>Micronizado<\/li>\n<\/ul>\n<p>O enxofre elementar granulado e o enxofre elementar micronizado se diferem, basicamente, pelo tamanho m\u00e9dio da part\u00edcula final.<\/p>\n<p>J\u00e1 o enxofre elementar pastilhado \u00e9 uma mistura do enxofre com um tipo de argila chamada bentonita. Quando aplicado no solo, a umidade faz com que a bentonita se expanda, disponibilizando o enxofre para o solo.<\/p>\n<p>Essas diferen\u00e7as das formas do enxofre elementar v\u00e3o impactar diretamente na sua efici\u00eancia agr\u00edcola. Mas como exatamente isso acontece e qual o principal problema do enxofre elementar pastilhado?<\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/blog.verde.ag\/pt\/e-book-fontes-de-enxofre-usadas-na-agricultura\/\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2023\/02\/e-book01\u2013fontes-de-enxofre-usadas-na-agricultura.jpg\" alt=\"-\" width=\"800\" height=\"1000\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/blog.verde.ag\/pt\/e-book-fontes-de-enxofre-usadas-na-agricultura\/\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2023\/02\/Banner_Ebook_Blog_1_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\t\r\n<\/div>\n<h2>Os problemas do enxofre pastilhado<\/h2>\n<p>Um dos principais problemas do enxofre elementar pastilhado est\u00e1 justamente na depend\u00eancia da umidade para que a bentonita se expanda e libere o enxofre para o solo.\u00a0 Isso faz com que o agricultor precise estar bastante atento \u00e0s condi\u00e7\u00f5es de umidade do solo para que a aduba\u00e7\u00e3o com essa forma do enxofre seja eficiente.<\/p>\n<p>Outro problema que diminui a efici\u00eancia do enxofre elementar pastilhado est\u00e1 relacionado com o tamanho das suas part\u00edculas. No artigo <em>Sulfur modulates yield and storage proteins in soybean grains,<\/em> Thiago Bergamini Iba\u00f1ez, da Universidade Estadual de S\u00e3o Paulo (UNESP), juntamente com outros pesquisadores, avaliou os efeitos do uso do enxofre na cultura de soja e identificou que \u201cO tamanho da part\u00edcula do enxofre pastilhado e do enxofre micronizado (ESPO) foi um fator chave para a disponibilidade de enxofre para a soja\u201d\u00a0.<\/p>\n<p>Assim como as part\u00edculas do enxofre elementar granulado, as part\u00edculas do enxofre pastilhado s\u00e3o maiores, o que faz com que a distribui\u00e7\u00e3o delas no solo n\u00e3o aconte\u00e7a de maneira homog\u00eanea. Assim, algumas \u00e1reas podem receber mais enxofre do que outras. Isso faz com que possa haver uma super aduba\u00e7\u00e3o em alguns pontos da lavoura e pontos com defici\u00eancia do enxofre.<\/p>\n<div style=\"text-align: center;\"><img decoding=\"async\" class=\"size-full wp-image-2621 aligncenter\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2021\/03\/Comparacao-da-distribuicao-do-enxofre-granulado-ou-pastilhado-e-o-BAKS.png\" alt=\"Compara\u00e7\u00e3o da distribui\u00e7\u00e3o do enxofre granulado ou pastilhado e o BAKS\" width=\"500\" height=\"247\" title=\"\"><\/div>\n<p style=\"text-align: center;\"><em style=\"font-size: 12px;\">Compara\u00e7\u00e3o da distribui\u00e7\u00e3o do enxofre granulado ou pastilhado e o BAKS\u00ae, <a href=\"https:\/\/blog.verde.ag\/pt\/baks\/entenda-o-que-e-o-baks-e-as-suas-vantagens-para-uma-nova-agricultura\/\">fertilizante com enxofre micronizado da Verde Agritech<\/a>. O n\u00famero de part\u00edculas da ilustra\u00e7\u00e3o \u00e9 baseado em uma distribui\u00e7\u00e3o de 30Kg por hectare, considerando um c\u00e1lculo proporcional entre o peso e concentra\u00e7\u00e3o de cada produto.<\/em><\/p>\n<p>Al\u00e9m disso, o tamanho maior das part\u00edculas tamb\u00e9m faz com que a \u00e1rea de contato com os microrganismos que atuam no processo de oxida\u00e7\u00e3o e disponibiliza\u00e7\u00e3o do enxofre para o solo seja menor. Isso faz com que esse processo seja menos eficiente.<\/p>\n<h2>Vale a pena usar enxofre elementar pastilhado?<\/h2>\n<p>O enxofre elementar pastilhado, apesar de ser uma fonte concentrada do nutriente que permite repor as necessidades da planta, possui algumas particularidades que limitam seu uso. A distribui\u00e7\u00e3o menos homog\u00eanea e a menor \u00e1rea de contato com os microrganismos que oxidam e disponibilizam o enxofre para o solo s\u00e3o os dois principias principais desafios que o insumo ainda enfrenta.<\/p>\n<p>Al\u00e9m disso, por causa da depend\u00eancia de condi\u00e7\u00f5es espec\u00edficas de umidade do solo para que a bentonita possa liberar o enxofre, \u00e9 preciso que o agricultor esteja mais atento a esse fator.<\/p>\n<p>Outras formas de aplica\u00e7\u00e3o do enxofre elementar, como o <a href=\"https:\/\/blog.verde.ag\/pt\/encontro-com-gigantes\/saiba-quais-sao-as-vantagens-do-enxofre-elementar-micronizado-para-a-sua-lavoura\/\">enxofre elementar micronizado<\/a>, oferecem resultados melhores e mais eficientes para que o agricultor tenha uma lavoura com mais qualidade e com mais produtividade.<\/p>\n<div class=\"shortcode_mobile\"><!--mobile-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-MOBILE\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Mobile.jpg\" alt=\"-\" width=\"800\" height=\"400\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n<div class=\"shortcode_desktop\"><!--desktop-->\r\n<p><a href=\"https:\/\/conteudo.verde.ag\/baks-fertilizante\/?utm_source=blog&amp;utm_campaign=Blog||Artigo&amp;utm_adset_name=BAKS-BANNER-DESKTOP\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-10080\" src=\"https:\/\/blog.verde.ag\/pt\/wp-content\/uploads\/2024\/04\/BAKS_Banner_Desktop.jpg\" alt=\"-\" width=\"800\" height=\"200\" title=\"\"><\/a><\/p>\r\n<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 o enxofre elementar pastilhado uma forma eficiente  de fornecer enxofre para as plantas.<\/p>\n","protected":false},"author":7,"featured_media":2622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[197],"tags":[138,141,139,885],"_links":{"self":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/2619"}],"collection":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":0,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/posts\/2619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media\/2622"}],"wp:attachment":[{"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/media?parent=2619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/categories?post=2619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.verde.ag\/pt\/wp-json\/wp\/v2\/tags?post=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}